{"id":40539,"date":"2025-10-23T20:32:34","date_gmt":"2025-10-24T04:32:34","guid":{"rendered":"https:\/\/kwoco-plc.com\/?page_id=40539"},"modified":"2025-10-23T20:33:13","modified_gmt":"2025-10-24T04:33:13","slug":"omron-nx-od4256","status":"publish","type":"page","link":"https:\/\/kwoco-plc.com\/ro\/product\/omron-nx-od4256\/","title":{"rendered":"Unitate de ie\u0219ire digital\u0103 Omron NX-OD4256 \u00een stoc"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"40539\" class=\"elementor elementor-40539\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77af0ae0 e-flex e-con-boxed e-con e-parent\" data-id=\"77af0ae0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bec8a26 rank_math_breadcrumb elementor-widget elementor-widget-shortcode\" data-id=\"6bec8a26\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"pesmet\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Acas\u0103<\/span><\/p><\/nav><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49a7c042 e-con-full e-flex e-con e-parent\" data-id=\"49a7c042\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36421f95 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"36421f95\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dae16b2 e-flex e-con-boxed e-con e-parent\" data-id=\"4dae16b2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9c36fa0 e-con-full e-flex e-con e-child\" data-id=\"9c36fa0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-642376c0 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"642376c0\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-carousel.min.css\">\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"642376c0\" data-elementor-lightbox-title=\"NX-OD4256\" data-elementor-lightbox-description=\"NX-OD4256\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1NDQsInVybCI6Imh0dHBzOlwvXC9rd29jby1wbGMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMFwvTlgtT0Q0MjU2LTUuanBnIiwic2xpZGVzaG93IjoiNjQyMzc2YzAifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-5.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"642376c0\" data-elementor-lightbox-title=\"NX-OD4256\" data-elementor-lightbox-description=\"NX-OD4256\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1NDEsInVybCI6Imh0dHBzOlwvXC9rd29jby1wbGMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMFwvTlgtT0Q0MjU2LTIuanBnIiwic2xpZGVzaG93IjoiNjQyMzc2YzAifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-2.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"642376c0\" data-elementor-lightbox-title=\"NX-OD4256\" data-elementor-lightbox-description=\"NX-OD4256\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1NDMsInVybCI6Imh0dHBzOlwvXC9rd29jby1wbGMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMFwvTlgtT0Q0MjU2LTQuanBnIiwic2xpZGVzaG93IjoiNjQyMzc2YzAifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-4.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"642376c0\" data-elementor-lightbox-title=\"NX-OD4256\" data-elementor-lightbox-description=\"NX-OD4256\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1NDIsInVybCI6Imh0dHBzOlwvXC9rd29jby1wbGMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMFwvTlgtT0Q0MjU2LTMuanBnIiwic2xpZGVzaG93IjoiNjQyMzc2YzAifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-3.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"642376c0\" data-elementor-lightbox-title=\"NX-OD4256\" data-elementor-lightbox-description=\"NX-OD4256\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1NDAsInVybCI6Imh0dHBzOlwvXC9rd29jby1wbGMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMFwvTlgtT0Q0MjU2LTEuanBnIiwic2xpZGVzaG93IjoiNjQyMzc2YzAifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Urm\u0103torul<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-thumbnails-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-5.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-2.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-4.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-3.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"NX-OD4256\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/10\/NX-OD4256-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ef14c4e e-flex e-con-boxed e-con e-child\" data-id=\"7ef14c4e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50581656 elementor-widget elementor-widget-heading\" data-id=\"50581656\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Unitate de ie\u0219ire digital\u0103 Omron NX-OD4256 \u00een stoc<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9803373 elementor-widget elementor-widget-text-editor\" data-id=\"9803373\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>8 ie\u0219iri digitale, vitez\u0103 standard, PNP 24 V CC, 0,5 A\/punct, unitate 4 A\/NX, conector push-in f\u0103r\u0103 \u0219uruburi, l\u0103\u021bime 12 mm.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a2528b4 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"2a2528b4\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 26-02-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"40539\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"2a2528b4\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNume\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nume\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t* E-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"* E-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMesaj\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"7\" placeholder=\"Mesaj\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_e079494 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_e079494\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfQP_ApAAAAAGkOmyxAEbGv0N0eOKw7gxJuRyP5\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trimite<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"ro\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30717cba elementor-widget elementor-widget-text-editor\" data-id=\"30717cba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>* Ave\u021bi nevoie de mai multe detalii? Echipa noastr\u0103 este gata s\u0103 v\u0103 ajute \u2013 nu ezita\u021bi s\u0103 ne \u00eentreba\u021bi!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d9a0e73 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d9a0e73\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13cfb987 e-flex e-con-boxed e-con e-parent\" data-id=\"13cfb987\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24c33e28 elementor-widget elementor-widget-heading\" data-id=\"24c33e28\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caracteristici cheie \u0219i specifica\u021bii tehnice<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20e05ec7 elementor-widget elementor-widget-text-editor\" data-id=\"20e05ec7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Aceast\u0103 unitate compact\u0103 simplific\u0103 automatizarea. Este u\u0219or de instalat \u0219i se conecteaz\u0103 perfect la sistemul dumneavoastr\u0103. Datorit\u0103 vitezei sale mari \u0219i designului robust, aceast\u0103 unitate \u00eembun\u0103t\u0103\u021be\u0219te performan\u021ba ma\u0219inii dumneavoastr\u0103.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b01de5 elementor-widget elementor-widget-html\" data-id=\"38b01de5\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"overflow-x: auto; width: 100%; font-family: oswald;\">\n<table>\n<tbody>\n<tr>\n<th>Articol<\/th>\n<th>Caietul de sarcini<\/th>\n<\/tr>\n<tr>\n<td>Model<\/td>\n<td>NX-OD4256<\/td>\n<\/tr>\n<tr>\n<td>Nume produs<\/td>\n<td>Unitate de ie\u0219ire cu tranzistor<\/td>\n<\/tr>\n<tr>\n<td>Num\u0103rul de ie\u0219iri<\/td>\n<td>8 puncte<\/td>\n<\/tr>\n<tr>\n<td>I\/O intern\u0103 comun\u0103<\/td>\n<td>PNP<\/td>\n<\/tr>\n<tr>\n<td>Tensiune nominal\u0103<\/td>\n<td>24 VDC<\/td>\n<\/tr>\n<tr>\n<td>Curent maxim de sarcin\u0103<\/td>\n<td>0,5 A\/punct, 4 A\/unitate<\/td>\n<\/tr>\n<tr>\n<td>Timp de r\u0103spuns PORNIT\/OPRIT<\/td>\n<td>0,5 ms maxim \/ 1,0 ms maxim<\/td>\n<\/tr>\n<tr>\n<td>Conexiune extern\u0103<\/td>\n<td>Bloc terminal cu prindere f\u0103r\u0103 \u0219uruburi (16 terminale)<\/td>\n<\/tr>\n<tr>\n<td>Func\u021bie de protec\u021bie<\/td>\n<td>Cu protec\u021bie la scurtcircuitul sarcinii<\/td>\n<\/tr>\n<tr>\n<td>Dimensiuni (L x A x A)<\/td>\n<td>12 mm x 100 mm x 71 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-134d4396 elementor-widget elementor-widget-heading\" data-id=\"134d4396\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Simplifica\u021bi-v\u0103 configurarea cu unitatea push-in Omron NX-OD4256<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60ef523 elementor-widget elementor-widget-text-editor\" data-id=\"60ef523\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Aceast\u0103 unitate folose\u0219te un conector push-in f\u0103r\u0103 \u0219uruburi. Aceasta \u00eenseamn\u0103 c\u0103 \u00eel pute\u021bi conecta foarte rapid. Trebuie doar s\u0103 \u00eempinge\u021bi firul. Firele r\u0103m\u00e2n la locul lor, chiar \u0219i \u00een cazul vibra\u021biilor ma\u0219inii. Acest lucru reduce riscul unor conexiuni sl\u0103bite care pot opri produc\u021bia.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67a370b4 elementor-widget elementor-widget-heading\" data-id=\"67a370b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Performan\u021b\u0103 de mare vitez\u0103 pentru ie\u0219ire digital\u0103 solicitant\u0103<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a363ad elementor-widget elementor-widget-text-editor\" data-id=\"7a363ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Omron NX-OD4256 este construit pentru sarcini de mare vitez\u0103. Reac\u021bioneaz\u0103 incredibil de rapid la semnalele de control. Acest lucru \u00eel face ideal pentru aplica\u021bii care necesit\u0103 ac\u021biuni precise \u0219i prompte. Unitatea ajut\u0103 ma\u0219inile dumneavoastr\u0103 s\u0103 func\u021bioneze mai rapid \u0219i mai precis. Indiferent dac\u0103 controla\u021bi valve, l\u0103mpi sau relee, NX-OD4256 ofer\u0103 performan\u021ba de care ave\u021bi nevoie.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e3da826 elementor-widget elementor-widget-heading\" data-id=\"7e3da826\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Design robust: 0,5A per punct \u0219i protec\u021bie \u00eencorporat\u0103<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48f65735 elementor-widget elementor-widget-text-editor\" data-id=\"48f65735\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>NX-OD4256 este o unitate de ie\u0219ire digital\u0103 robust\u0103 \u0219i puternic\u0103. Ofer\u0103 8 ie\u0219iri digitale, fiecare capabil\u0103 s\u0103 gestioneze p\u00e2n\u0103 la 0,5 A (0,5 A per punct). Cu un curent total maxim de 4 A pentru \u00eentreaga unitate, poate alimenta o gam\u0103 larg\u0103 de dispozitive. Acest lucru o face foarte flexibil\u0103 pentru designul ma\u0219inilor dumneavoastr\u0103.<\/p><p>Omron NX-OD4256 se protejeaz\u0103 \u0219i singur. Are protec\u021bie \u00eencorporat\u0103 la scurtcircuit. Dac\u0103 apare o eroare de cablare, unitatea este protejat\u0103 de deterior\u0103ri. Aceast\u0103 caracteristic\u0103 v\u0103 scute\u0219te de repara\u021bii costisitoare \u0219i de timpii de nefunc\u021bionare.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e659452 elementor-widget elementor-widget-heading\" data-id=\"4e659452\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integrare perfect\u0103 cu unitatea CPU \u0219i seria NX<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b98fa3 elementor-widget elementor-widget-text-editor\" data-id=\"38b98fa3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Omron NX-OD4256 este conceput pentru o integrare u\u0219oar\u0103. Se conecteaz\u0103 direct la placa de baz\u0103 din seria NX, func\u021bion\u00e2nd al\u0103turi de unitatea CPU \u0219i alte module de intrare NX-ID. Acest lucru creeaz\u0103 un sistem de control curat \u0219i unificat, f\u0103r\u0103 cablare suplimentar\u0103.<\/p><p>Unitatea accept\u0103 protocoale de comunica\u021bie standard prin intermediul unit\u0103\u021bii CPU. Acest lucru faciliteaz\u0103 ad\u0103ugarea la sisteme noi sau existente. Platforma seriei NX ofer\u0103 un singur mediu software, Sysmac Studio, pentru configurare. Acest lucru simplific\u0103 programarea \u0219i reduce timpul de configurare.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e68dca elementor-widget elementor-widget-heading\" data-id=\"43e68dca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fi\u0219\u0103 tehnic\u0103 a produsului Omron NX-OD4256<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11291846 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"11291846\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx1_datasheet.pdf\" target=\"_blank\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx1_datasheet.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tFi\u0219\u0103 tehnic\u0103 seria Omron NX .pdf\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-411cbd1f elementor-widget elementor-widget-heading\" data-id=\"411cbd1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00centreb\u0103ri frecvente<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf86f95 elementor-widget elementor-widget-accordion\" data-id=\"cf86f95\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-accordion{text-align:start}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2171\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2171\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Care este principala aplica\u021bie pentru Omron NX-OD4256?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2171\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2171\"><p>NX-OD4256 este o unitate de ie\u0219ire digital\u0103 utilizat\u0103 \u00een automatizarea industrial\u0103 pentru a controla dispozitive precum actuatoare, indicatoare \u0219i motoare mici care necesit\u0103 un semnal PNP de 24 V CC.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2172\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2172\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Este dificil de instalat aceast\u0103 unitate?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2172\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2172\"><p>Nu, este foarte u\u0219or de instalat. Dispune de un bloc terminal push-in pentru cablare f\u0103r\u0103 unelte \u0219i se fixeaz\u0103 pe o \u0219in\u0103 DIN standard.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2173\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2173\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Cu ce controlere este compatibil NX-OD4256?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2173\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2173\"><p>Face parte din seria Omron NX \u0219i este conceput s\u0103 func\u021bioneze cu unit\u0103\u021bi CPU din seria NX \u0219i unit\u0103\u021bi de cuplare EtherCAT pentru comunicare \u0219i control f\u0103r\u0103 probleme.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2174\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2174\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ce fel de protec\u021bie ofer\u0103 NX-OD4256?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2174\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2174\"><p>Aceast\u0103 unitate este dotat\u0103 cu protec\u021bie \u00eencorporat\u0103 la scurtcircuitul sarcinii, care protejeaz\u0103 circuitele de ie\u0219ire de deteriorarea cauzat\u0103 de defectele de cablare.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What is the main application for the Omron NX-OD4256?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>The\\u00a0NX-OD4256\\u00a0is a\\u00a0digital output\\u00a0unit\\u00a0used in industrial\\u00a0automation\\u00a0to control devices like actuators, indicators, and small motors that require a\\u00a024 VDC\\u00a0PNP\\u00a0signal.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Is this unit difficult to install?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>No, it is very easy to install. It features a\\u00a0push-in\\u00a0terminal block for tool-free wiring and snaps onto a standard\\u00a0DIN rail.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What controllers is the NX-OD4256 compatible with?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>It is part of the\\u00a0Omron\\u00a0NX series\\u00a0and is designed to work with\\u00a0NX-series\\u00a0CPU Units and EtherCAT Coupler Units for seamless\\u00a0communication\\u00a0and control.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What kind of protection does the NX-OD4256 offer?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>This\\u00a0unit\\u00a0comes with built-in load short-circuit protection, which protects the output circuits from damage due to wiring faults.<\\\/p>\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f54fad1 e-flex e-con-boxed e-con e-parent\" data-id=\"7f54fad1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e02903f e-con-full e-flex e-con e-child\" data-id=\"3e02903f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1b496fe5 e-flex e-con-boxed e-con e-child\" data-id=\"1b496fe5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc10fad elementor-widget elementor-widget-heading\" data-id=\"5dc10fad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produs \u00eenrudit<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-203e8750 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"203e8750\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-193fbb2e elementor-grid-4 elementor-grid-mobile-2 elementor-posts__hover-none elementor-grid-tablet-2 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-widget elementor-widget-posts\" data-id=\"193fbb2e\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_mobile&quot;:&quot;2&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;cards_masonry&quot;:&quot;yes&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26759 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/cp1e-n20dt-d\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cp1e-n20dt-d-1.webp\" class=\"attachment-full size-full wp-image-26765\" alt=\"cp1e-n20dt-d (1)\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cp1e-n20dt-d-1.webp 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cp1e-n20dt-d-1-300x225.webp 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cp1e-n20dt-d-1-1024x768.webp 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cp1e-n20dt-d-1-768x576.webp 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cp1e-n20dt-d-1-1536x1152.webp 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/cp1e-n20dt-d\/\" >\n\t\t\t\tPLC compact Omron CP1E-N20DT-D\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/cp1e-n20dt-d\/\" aria-label=\"Citi\u021bi mai multe despre Omron CP1E-N20DT-D Compact PLC\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-41770 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-nx-ec0122\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/04\/NX-EC0122-5.jpg\" class=\"attachment-full size-full wp-image-41775\" alt=\"NX-EC0122\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/04\/NX-EC0122-5.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/04\/NX-EC0122-5-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/04\/NX-EC0122-5-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/04\/NX-EC0122-5-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/04\/NX-EC0122-5-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/04\/NX-EC0122-5-16x12.jpg 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-nx-ec0122\/\" >\n\t\t\t\tUnitate de intrare encoder incremental Omron NX-EC0122\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-nx-ec0122\/\" aria-label=\"Citi\u021bi mai multe despre unitatea de intrare pentru encoder incremental Omron NX-EC0122\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-9513 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-cpu-backplane-cs1d-bc052\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1d-bc052-1.jpg\" class=\"attachment-full size-full wp-image-9516\" alt=\"cs1d-bc052 (1)\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1d-bc052-1.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1d-bc052-1-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1d-bc052-1-1024x768.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1d-bc052-1-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1d-bc052-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-cpu-backplane-cs1d-bc052\/\" >\n\t\t\t\tOmron CPU Backplane CS1D-BC052\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-cpu-backplane-cs1d-bc052\/\" aria-label=\"Citi\u021bi mai multe despre Omron CPU Backplane CS1D-BC052\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-815 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-nx1p2-cpu-unit-nx1p2-1040dt1\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"721\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx1p2-1040dt1.jpg\" class=\"attachment-full size-full wp-image-818\" alt=\"nx1p2-1040dt1\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx1p2-1040dt1.jpg 960w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx1p2-1040dt1-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx1p2-1040dt1-768x577.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-nx1p2-cpu-unit-nx1p2-1040dt1\/\" >\n\t\t\t\tUnitate CPU OMRON NX1P2 NX1P2-1040DT1\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/omron-nx1p2-cpu-unit-nx1p2-1040dt1\/\" aria-label=\"Citi\u021bi mai multe despre Unitatea CPU OMRON NX1P2 NX1P2-1040DT1\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28264c23 e-con-full e-flex e-con e-child\" data-id=\"28264c23\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-577fc8ff e-flex e-con-boxed e-con e-child\" data-id=\"577fc8ff\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-768d4853 elementor-widget elementor-widget-heading\" data-id=\"768d4853\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Toate nevoile dvs. de control<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5fb954 elementor-widget elementor-widget-text-editor\" data-id=\"6a5fb954\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nu v\u0103 pute\u021bi g\u0103si marca? Contacta\u021bi-ne pentru asisten\u021b\u0103 personalizat\u0103.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43c9365c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"43c9365c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00centreba\u021bi acum<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>8 ie\u0219iri digitale, vitez\u0103 standard, PNP 24 V CC, 0,5 A\/punct, unitate 4 A\/NX, conector push-in f\u0103r\u0103 \u0219uruburi, l\u0103\u021bime 12 mm.<\/p>","protected":false},"author":1,"featured_media":40544,"parent":76,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[56,16,7,70],"_links":{"self":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/40539"}],"collection":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/comments?post=40539"}],"version-history":[{"count":5,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/40539\/revisions"}],"predecessor-version":[{"id":40549,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/40539\/revisions\/40549"}],"up":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/76"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/media\/40544"}],"wp:attachment":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/media?parent=40539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/categories?post=40539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/tags?post=40539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}