{"id":3230,"date":"2024-05-21T07:55:20","date_gmt":"2024-05-21T07:55:20","guid":{"rendered":"https:\/\/kwoco-plc.com\/?page_id=3230"},"modified":"2025-02-16T18:09:39","modified_gmt":"2025-02-17T02:09:39","slug":"delta-servo-drive-asd-b2-1521-b","status":"publish","type":"page","link":"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-b2-1521-b\/","title":{"rendered":"Servo Drive Delta ASD-B2-1521-B"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3230\" class=\"elementor elementor-3230\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46ebb41f e-flex e-con-boxed e-con e-parent\" data-id=\"46ebb41f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2734b2a6 rank_math_breadcrumb elementor-widget elementor-widget-shortcode\" data-id=\"2734b2a6\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"pesmet\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Acas\u0103<\/span><\/p><\/nav><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a79f5d1 e-con-full e-flex e-con e-parent\" data-id=\"a79f5d1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4083d87d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4083d87d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f2130c9 e-flex e-con-boxed e-con e-parent\" data-id=\"3f2130c9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6710dc3f e-flex e-con-boxed e-con e-child\" data-id=\"6710dc3f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-283775ae elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"283775ae\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-carousel.min.css\">\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-asd-b2-1521-b-600x451-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"283775ae\" data-elementor-lightbox-title=\"delta-asd-b2-1521-b-600x451\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI0MywidXJsIjoiaHR0cHM6XC9cL2t3b2NvLXBsYy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA1XC9kZWx0YS1hc2QtYjItMTUyMS1iLTYwMHg0NTEtMS5qcGciLCJzbGlkZXNob3ciOiIyODM3NzVhZSJ9\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-asd-b2-1521-b-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-1.5kw-servo-600x451-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"283775ae\" data-elementor-lightbox-title=\"delta-1.5kw-servo-600x451\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI0MiwidXJsIjoiaHR0cHM6XC9cL2t3b2NvLXBsYy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA1XC9kZWx0YS0xLjVrdy1zZXJ2by02MDB4NDUxLTEuanBnIiwic2xpZGVzaG93IjoiMjgzNzc1YWUifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-1.5kw-servo-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-1.5kw-asd-b2-1521-600x451-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"283775ae\" data-elementor-lightbox-title=\"delta-1.5kw-asd-b2-1521-600x451\" data-elementor-lightbox-description=\"asd-b2-1521-b\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI0MSwidXJsIjoiaHR0cHM6XC9cL2t3b2NvLXBsYy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA1XC9kZWx0YS0xLjVrdy1hc2QtYjItMTUyMS02MDB4NDUxLTEuanBnIiwic2xpZGVzaG93IjoiMjgzNzc1YWUifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-1.5kw-asd-b2-1521-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b-servo-600x451-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"283775ae\" data-elementor-lightbox-title=\"asd-b2-1521-b-servo-600x451\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI0MCwidXJsIjoiaHR0cHM6XC9cL2t3b2NvLXBsYy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA1XC9hc2QtYjItMTUyMS1iLXNlcnZvLTYwMHg0NTEtMS5qcGciLCJzbGlkZXNob3ciOiIyODM3NzVhZSJ9\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b-servo-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"283775ae\" data-elementor-lightbox-title=\"asd-b2-1521-b\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzIzOSwidXJsIjoiaHR0cHM6XC9cL2t3b2NvLXBsYy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzA1XC9hc2QtYjItMTUyMS1iLmpwZyIsInNsaWRlc2hvdyI6IjI4Mzc3NWFlIn0%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Urm\u0103torul<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-thumbnails-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-asd-b2-1521-b-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-1.5kw-servo-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/delta-1.5kw-asd-b2-1521-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b-servo-600x451-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-b2-1521-b\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ce2691c e-flex e-con-boxed e-con e-child\" data-id=\"7ce2691c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52c86d63 elementor-widget elementor-widget-heading\" data-id=\"52c86d63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Servo Drive Delta ASD-B2-1521-B<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-384b54d1 elementor-widget elementor-widget-heading\" data-id=\"384b54d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Servomotor de mare capacitate din seria ASD-B2, 1500 W; Intrare 220 Volti; 1\/3 faza (PH); 8.3 Curentul de ie\u0219ire al armelor, potrivit pentru aplica\u021bii industriale solicitante care necesit\u0103 un control precis al mi\u0219c\u0103rii.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e0b273f elementor-widget elementor-widget-html\" data-id=\"3e0b273f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"overflow-x: auto;width: 100%;font-family: oswald;\">\r\n<table>\r\n    <tr>\r\n        <td>Marca<\/td>\r\n        <td>Delta<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>Num\u0103rul de model<\/td>\r\n        <td>ASD-B2-1521-B<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>Stat<\/td>\r\n        <td>\u00cen stoc<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>Stare<\/td>\r\n        <td>Original nou<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>garan\u021bie<\/td>\r\n        <td>12 luni<\/td>\r\n    <\/tr>   \r\n<\/table>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13cfde2 elementor-widget elementor-widget-button\" data-id=\"13cfde2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ob\u021bine\u021bi o cota\u021bie instantanee<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bb1c195 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1bb1c195\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1baec111 e-flex e-con-boxed e-con e-child\" data-id=\"1baec111\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-657642f5 e-flex e-con-boxed e-con e-child\" data-id=\"657642f5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e46b74b elementor-widget elementor-widget-heading\" data-id=\"1e46b74b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Categorii<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e02dffb elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6e02dffb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Delta<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servo Drive Delta ASDA-B2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5683d605 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5683d605\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5823af e-flex e-con-boxed e-con e-child\" data-id=\"e5823af\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c13a5f elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"4c13a5f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Asigurare global\u0103<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c322ced elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c322ced\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/100-new-original.png\" class=\"attachment-full size-full wp-image-27285\" alt=\"100% nou original\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eae540 elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"8eae540\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/12-months-warranty.png\" class=\"attachment-full size-full wp-image-27286\" alt=\"12 luni garantie\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4be47d elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a4be47d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/wordwide-shipping.png\" class=\"attachment-full size-full wp-image-27287\" alt=\"livrare la nivel mondial\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43ac049b e-flex e-con-boxed e-con e-parent\" data-id=\"43ac049b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a0d2c9d e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"3a0d2c9d\" data-element_type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"973\" aria-label=\"Filele. Deschide\u021bi elementele cu Enter sau Space, \u00eenchide\u021bi cu Escape \u0219i naviga\u021bi folosind tastele s\u0103ge\u021bi.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t\t\t<button id=\"e-n-tabs-title-9731\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-9731\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t\tParametri de produs\t\t\t\t<\/span>\n\t\t\t<\/button>\n\t\t\t\t\t<button id=\"e-n-tabs-title-9732\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-9732\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t\tVideo de produs\t\t\t\t<\/span>\n\t\t\t<\/button>\n\t\t\t\t\t<button id=\"e-n-tabs-title-9733\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-9733\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t\tFi\u0219a cu date\t\t\t\t<\/span>\n\t\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-9731\" role=\"tabpanel\" aria-labelledby=\"e-n-tabs-title-9731\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-4472b669 e-con-full e-flex e-con e-child\" data-id=\"4472b669\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f168215 elementor-widget elementor-widget-text-editor\" data-id=\"1f168215\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div style=\"overflow-x: auto; width: 100%; font-family: oswald;\">\n<table>\n<tbody>\n<tr>\n    <td colspan=\"3\"><strong>Model: Seria ASD-B2<\/strong><\/td>\n    <td><strong>100W<\/strong><\/td>\n    <td><strong>200W<\/strong><\/td>\n    <td><strong>400W<\/strong><\/td>\n    <td><strong>750W<\/strong><\/td>\n    <td><strong>1 kW<\/strong><\/td>\n    <td><strong>1,5 kW<\/strong><\/td>\n    <td><strong>2kW<\/strong><\/td>\n    <td><strong>3kW<\/strong><\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"3\"><\/td>\n    <td><strong>01<\/strong><\/td>\n    <td><strong>02<\/strong><\/td>\n    <td><strong>04<\/strong><\/td>\n    <td><strong>07<\/strong><\/td>\n    <td><strong>10<\/strong><\/td>\n    <td><strong>15<\/strong><\/td>\n    <td><strong>20<\/strong><\/td>\n    <td><strong>30<\/strong><\/td>\n    <\/tr>\n    <tr>\n    <td rowspan=\"6\">Modul de control al cuplului<\/td>\n    <td rowspan=\"3\"><strong>\u00a0<\/strong>&nbsp;\n    \n    Comand\u0103 de intrare analogic\u0103\n    \n    &nbsp;<\/td>\n    <td>Gama de tensiune<\/td>\n    <td colspan=\"8\">0 ~ \u00b110 VDC<\/td>\n    <\/tr>\n    <tr>\n    <td>Rezisten\u021b\u0103 de intrare<\/td>\n    <td colspan=\"8\">10KW<\/td>\n    <\/tr>\n    <tr>\n    <td>Constante de timp<\/td>\n    <td colspan=\"8\">2.2 noi<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Surs\u0103 de comand\u0103<\/td>\n    <td colspan=\"8\">Semnal analog extern \/ Parametri interni<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Strategia de netezire<\/td>\n    <td colspan=\"8\">Filtru trece-jos<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Func\u021bionare cu limit\u0103 de vitez\u0103<\/td>\n    <td colspan=\"8\">Setarea parametrilor sau prin intrarea analogic\u0103<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"3\">Ie\u0219ire monitor analogic<\/td>\n    <td colspan=\"8\">Semnalul monitorului poate fi setat \u00een func\u021bie de parametri (gama de tensiune de ie\u0219ire: \u00b1 8V)<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\"><strong>\u00a0<\/strong>&nbsp;\n    \n    <strong>\u00a0<\/strong>\n    \n    <strong>\u00a0<\/strong>\n    \n    <strong>\u00a0<\/strong>\n    \n    <strong>\u00a0<\/strong>\n    \n    Intr\u0103ri\/Ie\u0219iri digitale<\/td>\n    <td><strong>\u00a0<\/strong>&nbsp;\n    \n    <strong>\u00a0<\/strong>\n    \n    <strong>\u00a0<\/strong>\n    \n    Intr\u0103ri<\/td>\n    <td colspan=\"8\">Servo pornit, Resetare, comutare c\u00e2\u0219tig, \u0219tergere impuls, vitez\u0103 zero CLAMP, control invers al intr\u0103rii de comand\u0103, limita de vitez\u0103\/cuplu activat\u0103, selec\u021bie comenzi de vitez\u0103, comutare mod pozi\u021bie \/ vitez\u0103, comutare mod vitez\u0103 \/ cuplu, comutare mod cuplu \/ pozi\u021bie, oprire de urgen\u021b\u0103 , Limit\u0103 de blocare \u00eenainte\/\u00eenapoi, limit\u0103 de cuplu pentru operare \u00eenainte\/\u00eenapoi, intrare JOG \u00eenainte\/\u00eenapoi, selec\u021bie electronic\u0103 a raportului de vitez\u0103 (numerator) \u0219i intrare de blocare a impulsului<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\"><\/td>\n    <td rowspan=\"2\"><strong>\u00a0<\/strong>&nbsp;\n    \n    <strong>\u00a0<\/strong>\n    \n    Ie\u0219iri\n    \n    &nbsp;<\/td>\n    <td colspan=\"8\">Ie\u0219ire semnal codificator (A, B, Z Line Driver \/ Z Open collector)<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\"><\/td>\n    <td colspan=\"8\">Servo gata, Servo pornit, La vitez\u0103 zero, La viteza atins\u0103, La pozi\u021bionare finalizat\u0103, La limita de cuplu, Alarma servo (defec\u021biune servo) activat\u0103, Controlul fr\u00e2nei electromagnetice, Avertizare de suprasarcin\u0103 la ie\u0219ire, Avertizare servo activat\u0103<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"3\"><strong>\u00a0<\/strong>&nbsp;\n    \n    <strong>\u00a0<\/strong>\n    \n    <strong>\u00a0<\/strong>\n    \n    Func\u021bii de protec\u021bie<\/td>\n    <td colspan=\"8\">Supracurent, Supratensiune, Subtensiune, Motor supra\u00eenc\u0103lzit, Supra\u00eenc\u0103rcare, Supravitez\u0103, Abatere excesiv\u0103, Eroare de regenerare, Comand\u0103 anormal\u0103 de control al impulsului, Eroare codificator, Eroare de reglare, Oprire de urgen\u021b\u0103 activat\u0103, Eroare comutator de limitare \u00eenapoi\/\u00eenainte, Eroare de temperatur\u0103 IGBT, Eroare de comunicare serial\u0103, Intrare pierdere de faz\u0103 de alimentare, expirare a comunica\u021biei seriale, terminale cu protec\u021bie la scurtcircuit (borne U, V, W, CN1, CN2, CN3)<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"3\">Interfa\u021b\u0103 de comunicare<\/td>\n    <td colspan=\"8\">RS-232\uff0fRS-485<\/td>\n    <\/tr>\n    <tr>\n    <td rowspan=\"10\">Mediu<\/td>\n    <td colspan=\"2\">Locul de instalare<\/td>\n    <td colspan=\"8\">Loca\u021bie \u00een interior (f\u0103r\u0103 lumina direct\u0103 a soarelui), f\u0103r\u0103 lichide \u0219i gaze corozive (departe de cea\u021ba de ulei, gaz inflamabil, praf)<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Altitudine<\/td>\n    <td colspan=\"8\">Altitudine de 1000 m sau mai mic\u0103 deasupra nivelului m\u0103rii<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Presiunea atmosferic\u0103<\/td>\n    <td colspan=\"8\">86 kPa p\u00e2n\u0103 la 106 kPa<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Temperatura de operare<\/td>\n    <td colspan=\"8\">0oC la 55oC (32\u00b0F la 131\u00b0F) (Dac\u0103 temperatura de func\u021bionare este peste intervalul specificat, va fi necesar\u0103 r\u0103cirea for\u021bat\u0103)<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Temperatura de depozitare<\/td>\n    <td colspan=\"8\">-20\u2103 ~ 65\u2103<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Umiditate<\/td>\n    <td colspan=\"8\">0 p\u00e2n\u0103 la 90% (f\u0103r\u0103 condensare)<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Vibra\u021bie<\/td>\n    <td colspan=\"8\">2 2 9,80665 m\/s (1G) mai pu\u021bin de 20 Hz, 5,88 m\/s (0,6 G) 20 p\u00e2n\u0103 la 50 Hz<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Evaluare IP<\/td>\n    <td colspan=\"8\">IP20<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\">Sistem de alimentare<\/td>\n    <td colspan=\"8\">Sistem TN *4<\/td>\n    <\/tr>\n    <tr>\n    <td colspan=\"2\"><strong>\u00a0<\/strong>&nbsp;\n    \n    <strong>\u00a0<\/strong>\n    \n    Standarde\/cerin\u021b\u0103<\/td>\n    <td colspan=\"8\"><strong>\u00a0<\/strong>&nbsp;\n    \n    IEC\/EN 61800-5-1, UL 508C\n    \n    <strong>\u00a0<\/strong><\/td>\n    <\/tr>\n<\/tbody>\n<\/table>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-9732\" role=\"tabpanel\" aria-labelledby=\"e-n-tabs-title-9732\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-45160969 e-con-full e-flex e-con e-child\" data-id=\"45160969\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-279c69ee elementor-widget elementor-widget-video\" data-id=\"279c69ee\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=6WbelNmfAuM&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-9733\" role=\"tabpanel\" aria-labelledby=\"e-n-tabs-title-9733\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-1e13f852 e-con-full e-flex e-con e-child\" data-id=\"1e13f852\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50260b6d elementor-widget elementor-widget-image\" data-id=\"50260b6d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/Delta-ASDA-B2-datasheet.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"353\" height=\"490\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1.webp\" class=\"attachment-full size-full wp-image-35721\" alt=\"FI\u0218A CU DATE\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1.webp 353w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1-216x300.webp 216w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1-9x12.webp 9w\" sizes=\"(max-width: 353px) 100vw, 353px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-feac46b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"feac46b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/Delta-ASDA-B2-datasheet.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Desc\u0103rcare gratuit\u0103<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b00fcd e-flex e-con-boxed e-con e-parent\" data-id=\"7b00fcd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33ff9ec5 e-con-full e-flex e-con e-child\" data-id=\"33ff9ec5\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5f56725c e-flex e-con-boxed e-con e-child\" data-id=\"5f56725c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37f15cbd elementor-widget elementor-widget-heading\" data-id=\"37f15cbd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produs \u00eenrudit<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10f7701e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"10f7701e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2af0f46 elementor-grid-4 elementor-grid-mobile-2 elementor-posts__hover-none elementor-grid-tablet-2 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-widget elementor-widget-posts\" data-id=\"2af0f46\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_mobile&quot;:&quot;2&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3137 page type-page status-publish has-post-thumbnail hentry tag-delta tag-delta-servo-drives tag-products tag-servo-drive\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-a0421-ab\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"721\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/08\/asd-a0421-ab.jpg\" class=\"attachment-full size-full wp-image-32518\" alt=\"asd-a0421-ab\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/08\/asd-a0421-ab.jpg 960w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/08\/asd-a0421-ab-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/08\/asd-a0421-ab-768x577.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-a0421-ab\/\" >\n\t\t\t\tServo Drive Delta ASD-A0421-AB\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-a0421-ab\/\" aria-label=\"Citi\u021bi mai multe despre Delta Servo Drive ASD-A0421-AB\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3230 page type-page status-publish has-post-thumbnail hentry tag-delta tag-delta-servo-drives tag-products tag-servo-drive\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-b2-1521-b\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"721\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b.jpg\" class=\"attachment-full size-full wp-image-3239\" alt=\"asd-b2-1521-b\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b.jpg 960w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1521-b-768x577.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-b2-1521-b\/\" >\n\t\t\t\tServo Drive Delta ASD-B2-1521-B\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-b2-1521-b\/\" aria-label=\"Citi\u021bi mai multe despre Delta Servo Drive ASD-B2-1521-B\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3215 page type-page status-publish has-post-thumbnail hentry tag-delta tag-delta-servo-drives tag-products tag-servo-drive\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-b2-0721-b\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-0721-b-4.jpg\" class=\"attachment-full size-full wp-image-3222\" alt=\"asd-b2-0721-b\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-0721-b-4.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-0721-b-4-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-0721-b-4-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-0721-b-4-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-0721-b-4-1536x1153.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-b2-0721-b\/\" >\n\t\t\t\tServo Drive DELTA ASD-B2-0721-B\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-servo-drive-asd-b2-0721-b\/\" aria-label=\"Citi\u021bi mai multe despre DELTA Servo Drive ASD-B2-0721-B\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3173 page type-page status-publish has-post-thumbnail hentry tag-delta tag-delta-servo-drives tag-products tag-servo-drive\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-1kw-servo-drive-asd-b2-1021-b\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1021-b-5.jpg\" class=\"attachment-full size-full wp-image-3181\" alt=\"asd-b2-1021-b\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1021-b-5.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1021-b-5-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1021-b-5-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1021-b-5-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/asd-b2-1021-b-5-1536x1153.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-1kw-servo-drive-asd-b2-1021-b\/\" >\n\t\t\t\tServo Drive Delta 1kw ASD-B2-1021-B\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/ro\/product\/delta-1kw-servo-drive-asd-b2-1021-b\/\" aria-label=\"Citi\u021bi mai multe despre Servo Drive Delta 1kw ASD-B2-1021-B\" tabindex=\"-1\" >\n\t\t\tVezi mai multe \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31e6928a e-con-full e-flex e-con e-child\" data-id=\"31e6928a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-74fce6be e-flex e-con-boxed e-con e-child\" data-id=\"74fce6be\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a422dc0 elementor-widget elementor-widget-heading\" data-id=\"1a422dc0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Toate nevoile dvs. de control<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9716ea7 elementor-widget elementor-widget-text-editor\" data-id=\"9716ea7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nu v\u0103 pute\u021bi g\u0103si marca? Contacta\u021bi-ne pentru asisten\u021b\u0103 personalizat\u0103.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bde89a3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4bde89a3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00centreba\u021bi acum<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d89e5cc e-flex e-con-boxed e-con e-parent\" data-id=\"d89e5cc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25a7035 e-flex e-con-boxed e-con e-child\" data-id=\"25a7035\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-59c3ae4c e-flex e-con-boxed e-con e-child\" data-id=\"59c3ae4c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5008073b elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"5008073b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-th\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M149.333 56v80c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V56c0-13.255 10.745-24 24-24h101.333c13.255 0 24 10.745 24 24zm181.334 240v-80c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24h101.333c13.256 0 24.001-10.745 24.001-24zm32-240v80c0 13.255 10.745 24 24 24H488c13.255 0 24-10.745 24-24V56c0-13.255-10.745-24-24-24H386.667c-13.255 0-24 10.745-24 24zm-32 80V56c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24h101.333c13.256 0 24.001-10.745 24.001-24zm-205.334 56H24c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24zM0 376v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H24c-13.255 0-24 10.745-24 24zm386.667-56H488c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H386.667c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24zm0 160H488c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H386.667c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24zM181.333 376v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00cencepe\u021bi ast\u0103zi!\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDEBLOCA\u021aI SOLU\u021aII EFICIENTE \u2013 TRIMITE\u021aI CEREREA DVS. DE ASISTEN\u021a\u0102 IMMEDIAT\u0102.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66e670aa elementor-widget elementor-widget-text-editor\" data-id=\"66e670aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Porni\u021bi \u00eentr-o c\u0103l\u0103torie de achizi\u021bii f\u0103r\u0103 \u00eentreruperi cu noi. Dac\u0103 sunte\u021bi \u00een c\u0103utarea unei oferte de produs sau ave\u021bi nevoie de orice asisten\u021b\u0103 suplimentar\u0103, echipa noastr\u0103 este aici pentru a v\u0103 ghida \u00een fiecare pas.<\/p><p>Completa\u021bi acest formular pentru a \u00eencepe o conversa\u021bie adaptat\u0103 nevoilor dumneavoastr\u0103 specifice. \u00cen\u021belegem valoarea proiectului \u0219i timpul dumneavoastr\u0103.<\/p><p>Fi\u021bi siguri, informa\u021biile dvs. de e-mail r\u0103m\u00e2n strict confiden\u021biale pentru noi. Haide\u021bi s\u0103 colabor\u0103m pentru a v\u0103 \u00eembun\u0103t\u0103\u021bi opera\u021biunile ast\u0103zi.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30df9535 e-flex e-con-boxed e-con e-child\" data-id=\"30df9535\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83853d1 elementor-widget elementor-widget-heading\" data-id=\"83853d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cere\u021bi o cota\u021bie acum!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77e9813 elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-22716 elementor-widget-form\" data-id=\"77e9813\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 26-02-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"3230\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"77e9813\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNume\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nume\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMesaj\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mesaj\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_cb8daa8 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_cb8daa8\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfQP_ApAAAAAGkOmyxAEbGv0N0eOKw7gxJuRyP5\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon-right elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-telegram-plane\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M446.7 98.6l-67.6 318.8c-5.1 22.5-18.4 28.1-37.3 17.5l-103-75.9-49.7 47.8c-5.5 5.5-10.1 10.1-20.7 10.1l7.4-104.9 190.9-172.5c8.3-7.4-1.8-11.5-12.9-4.1L117.8 284 16.2 252.2c-22.1-6.9-22.5-22.1 4.6-32.7L418.2 66.4c18.4-6.9 34.5 4.1 28.5 32.2z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trimite<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"ro\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Previous Next Delta Servo Drive ASD-B2-1521-B Servo drive de mare capacitate din seria ASD-B2, 1500 W; Intrare 220 Volti; 1\/3 faza (PH); 8.3 Curentul de ie\u0219ire a armelor,<\/p>","protected":false},"author":1,"featured_media":3239,"parent":76,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[60,38,70,10],"class_list":["post-3230","page","type-page","status-publish","has-post-thumbnail","hentry","tag-delta","tag-delta-servo-drives","tag-products","tag-servo-drive"],"_links":{"self":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/3230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/comments?post=3230"}],"version-history":[{"count":46,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/3230\/revisions"}],"predecessor-version":[{"id":36899,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/3230\/revisions\/36899"}],"up":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/pages\/76"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/media\/3239"}],"wp:attachment":[{"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/media?parent=3230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/categories?post=3230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kwoco-plc.com\/ro\/wp-json\/wp\/v2\/tags?post=3230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}