{"id":39788,"date":"2025-08-07T20:19:59","date_gmt":"2025-08-08T04:19:59","guid":{"rendered":"https:\/\/kwoco-plc.com\/?p=39788"},"modified":"2026-07-05T19:11:55","modified_gmt":"2026-07-06T03:11:55","slug":"plc-programming-guide-for-beginners","status":"publish","type":"post","link":"https:\/\/kwoco-plc.com\/it\/plc-programming-guide-for-beginners\/","title":{"rendered":"Programmazione PLC: una guida definitiva per principianti\u00a0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"39788\" class=\"elementor elementor-39788\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-348b941e e-flex e-con-boxed e-con e-parent\" data-id=\"348b941e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-884e e-con-full e-flex e-con e-child\" data-id=\"884e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1857bb79 elementor-widget elementor-widget-heading\" data-id=\"1857bb79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Programmazione PLC: una guida definitiva per principianti\u00a0<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15331cfd elementor-widget elementor-widget-post-info\" data-id=\"15331cfd\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\"><link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-theme-elements.min.css\">\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-1d053df elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/author\/lightslategray-jaguar-242343-hostingersite-com\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-user-circle\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 104c-53 0-96 43-96 96s43 96 96 96 96-43 96-96-43-96-96-96zm0 144c-26.5 0-48-21.5-48-48s21.5-48 48-48 48 21.5 48 48-21.5 48-48 48zm0-240C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-49.7 0-95.1-18.3-130.1-48.4 14.9-23 40.4-38.6 69.6-39.5 20.8 6.4 40.6 9.6 60.5 9.6s39.7-3.1 60.5-9.6c29.2 1 54.7 16.5 69.6 39.5-35 30.1-80.4 48.4-130.1 48.4zm162.7-84.1c-24.4-31.4-62.1-51.9-105.1-51.9-10.2 0-26 9.6-57.6 9.6-31.5 0-47.4-9.6-57.6-9.6-42.9 0-80.6 20.5-105.1 51.9C61.9 339.2 48 299.2 48 256c0-110.3 89.7-200 200-200s200 89.7 200 200c0 43.2-13.9 83.2-37.3 115.9z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tkwoco-plc.com\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d341297 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"1d341297\" data-element_type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\tNel mondo odierno, in cui l&#039;automazione industriale e la produzione intelligente stanno rivoluzionando il mondo, il Controllore Logico Programmabile (PLC) \u00e8 diventato la &quot;mente&quot; centrale di ogni sistema automatico. Per le persone e le aziende che mirano a entrare o progredire nel campo dell&#039;automazione, padroneggiare i programmi PLC non \u00e8 solo un&#039;abilit\u00e0, ma la chiave del futuro.\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-692a240 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"692a240\" data-element_type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 26-02-2024 *\/\n.elementor-widget-table-of-contents .elementor-toc__header-title{color:var(--header-color)}.elementor-widget-table-of-contents.elementor-toc--collapsed .elementor-toc__toggle-button--collapse,.elementor-widget-table-of-contents:not(.elementor-toc--collapsed) .elementor-toc__toggle-button--expand{display:none}.elementor-widget-table-of-contents .elementor-widget-container{min-height:var(--box-min-height);border:var(--box-border-width,1px) solid var(--box-border-color,#9da5ae);border-radius:var(--box-border-radius,3px);background-color:var(--box-background-color);transition:min-height .4s;overflow:hidden}.elementor-toc__header{display:flex;align-items:center;justify-content:space-between;padding:var(--box-padding,20px);background-color:var(--header-background-color);border-bottom:var(--separator-width,1px) solid var(--box-border-color,#9da5ae)}.elementor-toc__header-title{font-size:18px;margin:0;color:var(--header-color)}.elementor-toc__toggle-button{cursor:pointer;display:inline-flex}.elementor-toc__toggle-button i{color:var(--toggle-button-color)}.elementor-toc__toggle-button svg{height:1em;width:1em;fill:var(--toggle-button-color)}.elementor-toc__spinner-container{text-align:center}.elementor-toc__spinner{font-size:2em}.elementor-toc__spinner.e-font-icon-svg{height:1em;width:1em}.elementor-toc__body{padding:var(--box-padding,20px);max-height:var(--toc-body-max-height);overflow-y:auto}.elementor-toc__body::-webkit-scrollbar{width:7px}.elementor-toc__body::-webkit-scrollbar-thumb{background-color:#babfc5;border-radius:10px}.elementor-toc__list-wrapper{list-style:none;padding:0}.elementor-toc__list-item{margin-bottom:.5em}.elementor-toc__list-item.elementor-item-active{font-weight:700}.elementor-toc__list-item .elementor-toc__list-wrapper{margin-top:.5em;margin-left:var(--nested-list-indent,1em)}.elementor-toc__list-item-text:hover{color:var(--item-text-hover-color);-webkit-text-decoration:var(--item-text-hover-decoration);text-decoration:var(--item-text-hover-decoration)}.elementor-toc__list-item-text.elementor-item-active{color:var(--item-text-active-color);-webkit-text-decoration:var(--item-text-active-decoration);text-decoration:var(--item-text-active-decoration)}.elementor-toc__list-item-text-wrapper{display:flex;align-items:center}.elementor-toc__list-item-text-wrapper:before,.elementor-toc__list-item-text-wrapper i{margin-right:8px;color:var(--marker-color)}.elementor-toc__list-item-text-wrapper svg{margin-right:8px;fill:var(--marker-color);height:var(--marker-size,.5em);width:var(--marker-size,.5em)}.elementor-toc__list-item-text-wrapper i{font-size:var(--marker-size,.5em)}.elementor-toc__list-item-text-wrapper:before{font-size:var(--marker-size,1em)}.elementor-toc--content-ellipsis .elementor-toc__list-item-text{white-space:nowrap;overflow:hidden;text-overflow:ellipsis}.elementor-toc__list-items--collapsible>.elementor-toc__list-wrapper>.elementor-toc__list-item>.elementor-toc__list-wrapper{display:none}.elementor-toc__heading-anchor{position:absolute}.elementor-toc__body .elementor-toc__list-item-text{color:var(--item-text-color);-webkit-text-decoration:var(--item-text-decoration);text-decoration:var(--item-text-decoration)}.elementor-toc__body .elementor-toc__list-item-text:hover{color:var(--item-text-hover-color);-webkit-text-decoration:var(--item-text-hover-decoration);text-decoration:var(--item-text-hover-decoration)}.elementor-toc__body .elementor-toc__list-item-text.elementor-item-active{color:var(--item-text-active-color);-webkit-text-decoration:var(--item-text-active-decoration);text-decoration:var(--item-text-active-decoration)}ol.elementor-toc__list-wrapper{counter-reset:item}ol.elementor-toc__list-wrapper .elementor-toc__list-item{counter-increment:item}ol.elementor-toc__list-wrapper .elementor-toc__list-item-text-wrapper:before{content:counters(item,\".\") \". \"}<\/style>\t\t<div class=\"elementor-toc__header\">\n\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tSommario\t\t\t<\/h4>\n\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__692a240\" aria-expanded=\"true\" aria-label=\"Apri l&#039;indice\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__692a240\" aria-expanded=\"true\" aria-label=\"Chiudi indice\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/div>\n\t\t\t\t\t<\/div>\n\t\t<div id=\"elementor-toc__692a240\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36cb5cef elementor-widget elementor-widget-text-editor\" data-id=\"36cb5cef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Questo articolo intende fornire una tabella di marcia strutturata e completa per principianti, esperti in transizione da altri mercati e designer che desiderano sistematizzare la propria conoscenza.<\/p><p>Esamineremo sicuramente le competenze fondamentali necessarie per la programmazione PLC, il confronto e la valutazione dei tradizionali <strong><a href=\"https:\/\/kwoco-plc.com\/it\/plc\/\">PLC<\/a> <\/strong>prodotti di automazione sul mercato e tracciare un percorso di comprensione efficace dal concetto alla pratica, aiutandoti a ottenere un vantaggio competitivo nel periodo del Settore 4.0.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-39797 size-full\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/08\/plc-programming-guide.jpg\" alt=\"guida alla programmazione plc\" width=\"713\" height=\"404\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/08\/plc-programming-guide.jpg 713w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/08\/plc-programming-guide-300x170.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/08\/plc-programming-guide-18x10.jpg 18w\" sizes=\"(max-width: 713px) 100vw, 713px\" \/><\/p><h2>Perch\u00e9 il PLC \u00e8 la \u201cvaluta forte\u201d del futuro<\/h2><p>Quando parliamo di &quot;Industria 4.0&quot;, &quot;Produzione Intelligente&quot; o &quot;Internet of Points (IoT)&quot;, immaginiamo un impianto di produzione del futuro estremamente automatizzato e basato sui dati. Dietro questa grande storia, che guida silenziosamente ogni specifica attivit\u00e0 sulla linea di produzione, c&#039;\u00e8 il Programmable Reasoning Controller (PLC).<\/p><p>Nato negli anni &#039;60 per sostituire i grandi e complessi armadi di controllo dei rel\u00e8, si \u00e8 poi evoluto in un sistema informatico commerciale che integra controllo, calcolo e comunicazione.<\/p><p>Dalle linee di saldatura nella produzione di veicoli alle linee di confezionamento nel settore alimentare, dai sistemi idrici urbani ai moderni centri di organizzazione logistica, i PLC sono onnipresenti.<\/p><p>Secondo un rapporto di MarketsandMarkets, si prevede che il mercato mondiale dei PLC continuer\u00e0 a crescere stabilmente, trainato dalla ricerca incessante del settore manifatturiero mondiale di maggiori prestazioni, qualit\u00e0 superiore e flessibilit\u00e0.<\/p><p>Per questo motivo, la conoscenza dei programmi PLC indica che hai acquisito la capacit\u00e0 di &quot;parlare&quot; con i moderni dispositivi industriali, il che lo rende un &quot;denaro contante&quot; indispensabile nella tua carriera specialistica.<\/p><p>Tuttavia, molti si sentono scoraggiati quando incontrano per la prima volta i PLC: &quot;Non ho alcuna competenza elettrica, posso scoprirlo?&quot; &quot;La conoscenza \u00e8 cos\u00ec complicata, da dove posso iniziare?&quot;<\/p><p>Questo breve articolo chiarir\u00e0 sicuramente questi dubbi e dimostrer\u00e0 che, con la tecnica ideale, chiunque pu\u00f2 comprendere sistematicamente i programmi PLC.<\/p><h2>I. Strutturare una base solida: i 3 pilastri dei programmi PLC.<\/h2><p>Cos\u00ec come per imparare una lingua \u00e8 necessario prima comprendere l&#039;alfabeto e la grammatica, per imparare i programmi PLC bisogna iniziare dalle sue parti pi\u00f9 essenziali.<\/p><h3>1. Il linguaggio delle macchine: apparecchiature numeriche<\/h3><p>Il mondo interno di un PLC \u00e8 un globo binario composto da &quot;0&quot; e &quot;1&quot;. Tutte le direzioni e i dati complessi vengono inevitabilmente ricondotti a questo tipo di segnale elettrico basilare (ON\/OFF).<\/p><p>Pertanto, il primo passo per scoprire i programmi PLC \u00e8 riconoscere i diversi sistemi numerici e le loro conversioni.<\/p><ul><li><strong>Binario<\/strong>: Il linguaggio operativo di base di un PLC, che comprende solo 0 e 1. Ad esempio, la visibilit\u00e0 o l&#039;assenza di un segnale di ingresso o lo stato di avvio\/arresto di un motore possono essere rappresentati da 1 e 0.<\/li><li><strong>Decimale<\/strong>: Il sistema di conteggio a noi pi\u00f9 familiare nella vita di tutti i giorni, composto dalle cifre da 0 a 9.<\/li><li><strong>Esadecimale<\/strong>: Creato per rappresentare in modo molto pi\u00f9 compatto i numeri binari lunghi, composti da 0-9 e AF. Viene utilizzato regolarmente per gestire indirizzi di memoria e interazione dati.<\/li><\/ul><p>Conclusione: \u00e8 necessario saper convertire il formato decimale in binario, poich\u00e9 i valori di riferimento dei timer e dei contatori PLC (in decimale) vengono memorizzati e rifiniti all&#039;interno in formato binario.<\/p><p>Tabella di conversione del sistema numerico.<\/p><table><thead><tr><th>Decimale<\/th><th>Binario<\/th><th>Esadecimale<\/th><th>Riepilogo<\/th><\/tr><\/thead><tbody><tr><td>0<\/td><td>0000<\/td><td>0<\/td><td>\u00a0<\/td><\/tr><tr><td>1<\/td><td>0001<\/td><td>1<\/td><td>\u00a0<\/td><\/tr><tr><td>7<\/td><td>0111<\/td><td>7<\/td><td>\u00a0<\/td><\/tr><tr><td>10<\/td><td>1010<\/td><td>\u00a0<\/td><td>A partire da 10, l&#039;esadecimale utilizza le lettere.<\/td><\/tr><tr><td>15<\/td><td>1111<\/td><td>F<\/td><td>\u00a0<\/td><\/tr><tr><td>16<\/td><td>0001 0000<\/td><td>10<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table><p><img decoding=\"async\" class=\"alignnone wp-image-39737 size-large\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-OD262-4-1024x769.jpg\" alt=\"Modello CJ1W-OD262\" width=\"1024\" height=\"769\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-OD262-4-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-OD262-4-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-OD262-4-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-OD262-4-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-OD262-4-16x12.jpg 16w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-OD262-4.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><h3>2. I contenitori delle informazioni: tipi di dati<\/h3><p>Se i sistemi numerici sono le lettere, allora i tipi di dati sono le regole che definiscono esattamente come organizzare queste lettere in &quot;parole&quot;.<\/p><p>In un PLC, le informazioni vengono memorizzate in diverse lunghezze e formati per adattarsi alle diverse esigenze applicative. Prendendo come esempio i PLC Siemens ampiamente utilizzati, i tipi di dati tipici sono:<\/p><ul><li><strong>Morso<\/strong>: La pi\u00f9 piccola unit\u00e0 di dati, con valore 0 o 1. Rappresenta un pulsante o un segnale di un&#039;unit\u00e0 di rilevamento.<\/li><li><strong>Byte<\/strong>: Composto da 8 piccoli pezzi.<\/li><li><strong>Parola<\/strong>: Composto da 2 byte (16 bit). Generalmente utilizzato per salvare numeri interi (Int).<\/li><li><strong>Doppia parola<\/strong>: Composto da 2 parole (32 bit). Pu\u00f2 essere utilizzato per memorizzare numeri interi pi\u00f9 grandi (DInt) o numeri reali.<\/li><li><strong>Reale\/Float<\/strong>: Un numero in virgola mobile utilizzato per rappresentare valori specifici con decimali, come il livello di temperatura o segnali analogici di stress. Occupa 32 bit di memoria.<\/li><\/ul><p>Relazioni e dimensioni dei tipi di dati.<\/p><table><thead><tr><th>Tipo di dati<\/th><th>Acronimo<\/th><th>Piccoli pezzi abitati<\/th><th>Intervallo di archiviazione\/Descrizione<\/th><\/tr><\/thead><tbody><tr><td>Morso<\/td><td>Un po<\/td><td>1<\/td><td>0 o 1<\/td><\/tr><tr><td>Byte<\/td><td>Byte<\/td><td>8<\/td><td>da 0 a 255<\/td><\/tr><tr><td>Parola\/Intero<\/td><td>Parola\/ Int<\/td><td>16<\/td><td>-32.768 a 32.767<\/td><\/tr><tr><td>Doppia parola\/doppio intero<\/td><td>DWord\/ DInt<\/td><td>32<\/td><td>-2.147.483.648 a 2.147.483.647<\/td><\/tr><tr><td>Vero<\/td><td>Autentico\/Drift<\/td><td>32<\/td><td>Numero in virgola mobile con decimali, ad esempio 3,14<\/td><\/tr><\/tbody><\/table><p>Riconoscere queste tipologie di informazioni \u00e8 fondamentale. L&#039;utilizzo di una tipologia di informazioni errata pu\u00f2 causare errori di programma o overflow di dati.<\/p><p>Ad esempio, se si mantiene un valore di temperatura che richiede una precisione decimale direttamente in una variabile Integer (Int), la componente frazionaria verr\u00e0 sicuramente tagliata.<\/p><h3>3. La regolazione della logica: algebra booleana<\/h3><p>L&#039;algebra booleana \u00e8 il cuore della programmazione basata sul ragionamento a scaletta. Specifica le relazioni razionali di base, costituite principalmente da &quot;AND&quot;, &quot;OR&quot; e &quot;NOT&quot;.<\/p><ul><li><strong>E<\/strong>: Il risultato \u00e8 1 solo se tutte le condizioni sono reali allo stesso tempo (1 ). Nel ragionamento a scaletta, questo \u00e8 rappresentato da chiamate in serie . Circostanza applicativa: una macchina pu\u00f2 avviarsi solo se il &quot;pulsante di arresto di emergenza non \u00e8 premuto&quot; (problema A = 1) E il &quot;pulsante di avvio \u00e8 premuto&quot; (condizione B = 1).<\/li><li><strong>O<\/strong>: Il risultato \u00e8 1 se almeno un problema \u00e8 vero (1). Nella logica ladder, questo \u00e8 rappresentato da chiamate in parallelo. Circostanza applicativa: una spia del sistema di allarme viene attivata se &quot;Il livello di temperatura \u00e8 elevato&quot; (Problema A = 1) OPPURE &quot;La pressione \u00e8 insolita&quot; (Condizione B = 1).<\/li><li><strong>NON<\/strong>: Il risultato \u00e8 l&#039;inverso del problema. Nel ragionamento a scaletta, questo \u00e8 rappresentato da una chiamata Generalmente Chiusa (NC). Scenario applicativo: quando il livello del serbatoio non \u00e8 completo (condizione A = 0), la pompa dovrebbe funzionare (uscita Y = 1). Questo problema viene applicato nel programma utilizzando una chiamata NC che sta per &quot;livello non completo&quot;.<\/li><\/ul><p>Conoscendo queste 3 operazioni standard e sensate, \u00e8 possibile leggere e creare la maggior parte dei programmi PLC essenziali.<\/p><p><img decoding=\"async\" class=\"alignnone wp-image-39698 size-large\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-ETN21-3-1024x769.jpg\" alt=\"CJ1W-ETN21\" width=\"1024\" height=\"769\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-ETN21-3-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-ETN21-3-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-ETN21-3-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-ETN21-3-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-ETN21-3-16x12.jpg 16w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-ETN21-3.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><h2>II. Confronto tra i principali prodotti di automazione PLC<\/h2><p>Dopo aver appreso le nozioni fondamentali, il passo successivo importante \u00e8 la scelta del marchio PLC ideale da studiare approfonditamente.<\/p><p>Diversi marchi hanno posizionamenti di mercato, programmi software e applicazioni settoriali diversi. Di seguito \u00e8 riportata una valutazione relativa di numerosi importanti marchi internazionali di PLC.<\/p><table style=\"border-collapse: collapse; width: 690px; height: 650px;\" border=\"0\" width=\"1025\" cellspacing=\"0\" cellpadding=\"0\"><tbody><tr style=\"height: 41.25pt;\"><td class=\"et2\" style=\"height: 41.25pt; width: 153.75pt;\" width=\"205\" height=\"55\">Attributo\/Nome del marchio<\/td><td class=\"et3\" style=\"width: 153.75pt;\" width=\"205\">Siemens<\/td><td class=\"et3\" style=\"width: 153.75pt;\" width=\"205\">Rockwell (<a href=\"https:\/\/kwoco-plc.com\/it\/allen-bradley\/\">Allen-Bradley<\/a>)<\/td><td class=\"et3\" style=\"width: 153.75pt;\" width=\"205\"><a href=\"https:\/\/kwoco-plc.com\/it\/mitsubishi\/\">Mitsubishi elettrico<\/a><\/td><td class=\"et4\" style=\"width: 153.75pt;\" width=\"205\"><a href=\"https:\/\/kwoco-plc.com\/it\/omron\/\">Omron<\/a><\/td><\/tr><tr style=\"height: 117.00pt;\"><td class=\"et5\" style=\"height: 117.00pt; width: 153.75pt;\" width=\"205\" height=\"156\">Serie di articoli principali<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Raccolta SIMATIC S7 (ad esempio, S7-1200, S7-1500)<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Raccolta Allen-Bradley Logix (ad esempio, CompactLogix, ControlLogix)<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Collezione MELSEC iQ-R\/Q\/FX<\/td><td class=\"et7\" style=\"width: 153.75pt;\" width=\"205\">Serie Sysmac NJ\/NX, serie CP<\/td><\/tr><tr style=\"height: 70.00pt;\"><td class=\"et5\" style=\"height: 70.00pt; width: 153.75pt;\" width=\"205\" height=\"93\">Mostra il programma software<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Sito TIA<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Studio 5000\/ RSLogix 5000<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">GX Works3\/ Sviluppatore GX<\/td><td class=\"et7\" style=\"width: 153.75pt;\" width=\"205\">Sysmac Studio\/CX-One<\/td><\/tr><tr style=\"height: 115.00pt;\"><td class=\"et5\" style=\"height: 115.00pt; width: 153.75pt;\" width=\"205\" height=\"153\">Vantaggi di mercato<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Leader del mercato europeo e mondiale; funzionalit\u00e0 potente e alta combinazione, eccelle nel controllo di processi complessi e complessi.<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Dominante nel mercato nordamericano; i prodotti sono durevoli e affidabili, con origini profonde in mercati importanti come quello automobilistico e petrolchimico.<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Leader nel mercato orientale; molto conveniente nei dispositivi di piccole dimensioni, nel controllo delle attivit\u00e0 e nella robotica.<\/td><td class=\"et7\" style=\"width: 153.75pt;\" width=\"205\">Solida presenza nella produzione di precisione, come quella dell&#039;elettronica e dei semiconduttori; stretta combinazione di unit\u00e0 di rilevamento e controllori.<\/td><\/tr><tr style=\"height: 115.00pt;\"><td class=\"et5\" style=\"height: 115.00pt; width: 153.75pt;\" width=\"205\" height=\"153\">Alla scoperta della curva<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Il software \u00e8 potente ma abbastanza semplice; i principianti hanno bisogno di tempo per adattarsi all&#039;ambiente integrato nel sito TIA.<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Strutturato in modo logico, ma le licenze delle applicazioni software sono costose, il che rende il corso meno piacevole per alcuni studenti.<\/td><td class=\"et6\" style=\"width: 153.75pt;\" width=\"205\">Interfaccia utente intuitiva del software e ampia raccolta di linee guida: la serie FX \u00e8 ideale per principianti e piccoli lavori.<\/td><td class=\"et7\" style=\"width: 153.75pt;\" width=\"205\">Linea di prodotti chiara e software altamente integrato; focalizzato sulla soluzione e relativamente facile da usare.<\/td><\/tr><\/tbody><\/table><p><strong>Raccomandazione per principianti<\/strong>:<\/p><ul><li>Se il vostro obiettivo sono impianti di grandi dimensioni o strumenti di fabbricazione europea, iniziare con Siemens S7-1200 e TIA Portal \u00e8 la scelta migliore, grazie alla sua elevata quota di mercato e alla leadership tecnica.<\/li><li>Se ti stai concentrando su dispositivi di piccole dimensioni o hai un budget limitato, la serie Mitsubishi FX \u00e8 un punto di partenza eccezionale, con abbondanti risorse di apprendimento e costi hardware piuttosto ridotti.<\/li><\/ul><h2>III. Dal concetto alla pratica: un percorso di apprendimento ad alta efficienza in quattro fasi<\/h2><p>La conoscenza accademica \u00e8 la base, ma solo il metodo pu\u00f2 costruire il grattacielo.\u00a0<\/p><p><strong>Fase 1: Simulazione del programma software per familiarizzare con l&#039;atmosfera<\/strong><\/p><p>Scarica e installa il software di simulazione del marchio selezionato (ad esempio, TIA Site, GX Works3). Senza acquistare hardware, utilizza la funzione di simulazione integrata per creare il tuo primo progetto &quot;Hello there World&quot;: un semplice circuito start-stop-latch.<\/p><p>Prendi confidenza con l&#039;interfaccia utente del software, impara a creare tag (variabili), a scrivere un ragionamento a scaletta e a scaricare e tenere traccia di un programma.<\/p><p><strong>Azione 2: Padroneggiare le istruzioni di base\u00a0<\/strong><\/p><p>Scoprire e mettere in pratica sistematicamente le funzioni fondamentali conformi:.<\/p><ul><li><strong>Linee guida Little Bit Logic<\/strong>: AND, OR, NOT, bobine di uscita e cos\u00ec via.<\/li><li><strong>Timer<\/strong>: On-Delay (BUNCH), Off-Delay (TOF) per implementare funzionalit\u00e0 come l&#039;inizio ritardato e l&#039;uscita posticipata.<\/li><li><strong>Contatori<\/strong>: Conteggio in avanti (CTU), Conteggio alla rovescia (CTD) per raccogliere i conteggi degli articoli, registrare i tempi dei cicli e cos\u00ec via.<\/li><li><strong> Linee guida per lo spostamento (MOV)<\/strong>: Per spostare i dati da un indirizzo di memoria a un altro.<\/li><\/ul><p><strong>Fase 3: affrontare gli studi di situazione standard<\/strong><\/p><p>Una volta comprese le istruzioni di base, prova a completare alcune attivit\u00e0 tradizionali di livello base, come:<\/p><ul><li style=\"font-weight: bold;\"><strong>Controllo avanti\/indietro del motore trifase.<\/strong><\/li><li style=\"font-weight: bold;\"><strong>Tensione abbassata stella-triangolo a partire da .<\/strong><\/li><li style=\"font-weight: bold;\"><strong>Controllo del traffico.<\/strong><\/li><li style=\"font-weight: bold;\"><strong>Controllo automatico del carrello alternativo.<\/strong><\/li><\/ul><p>Questi casi di studio ti aiuteranno sicuramente a collegare indicazioni specifiche in un quadro logico per risolvere problemi del mondo reale.<\/p><p><strong>Azione 4: Esplora le funzionalit\u00e0 avanzate e il metodo pratico<\/strong><\/p><p>Una volta acquisita dimestichezza con i programmi fondamentali, \u00e8 possibile passare ad aree pi\u00f9 avanzate:<\/p><ul><li><strong>Elaborazione del segnale analogico<\/strong>: Scopri come controllare i segnali provenienti da unit\u00e0 di rilevamento analogiche (livello di temperatura, pressione) ed eseguire il controllo PID.<\/li><li><strong>Conteggio ad alta velocit\u00e0 e uscita a impulsi<\/strong>: Utilizzato per collegare encoder e gestire motori elettrici passo-passo\/servo.<\/li><li><strong>Comunicazione e networking<\/strong>: Scopri lo scambio di informazioni tra PLC o tra un PLC e un <a href=\"https:\/\/kwoco-plc.com\/it\/hmi\/\">Interfaccia uomo-macchina<\/a> (Interfaccia uomo-macchina) o un computer gestionale.<\/li><li><strong>Cercare opportunit\u00e0 pratiche<\/strong>: Se possibile, acquista un pacchetto base PLC per esercitarti con il cablaggio elettrico e il debugging. Niente offre un senso di realizzazione e una comprensione pi\u00f9 profonda dell&#039;illuminazione diretta di una luce o del pilotaggio di un motore. Puoi anche fare riferimento ai requisiti e alle best practice di aziende autorevoli come l&#039;International Culture of Automation (ISA) per migliorare le tue competenze professionali.<\/li><\/ul><h2>Conclusione<\/h2><p>Conoscere i PLC non \u00e8 una tecnologia moderna irraggiungibile e pesante, ma un percorso di avanzamento delle competenze con un percorso e un ragionamento chiari.<\/p><p>I principi fondamentali sono: inizialmente, acquisire una solida conoscenza dei tre pilastri teorici: sistemi numerici, tipi di dati e procedure logiche. In secondo luogo, scegliere con attenzione un marchio PLC mainstream come piattaforma di apprendimento in base ai propri obiettivi lavorativi e alle esigenze del mercato. Infine, seguire un percorso strutturato dalla simulazione all&#039;applicazione pratica e dal semplice al complesso, interiorizzando le conoscenze accademiche in una capacit\u00e0 analitica sensata con pratica continua e sfide basate su progetti.<\/p><p>L&#039;ondata di automazione industriale \u00e8 ormai giunta e, in quanto elemento centrale di questa rivoluzione, l&#039;importanza del PLC non pu\u00f2 essere sopravvalutata.<\/p><p>Iniziare il tuo percorso formativo oggi non \u00e8 solo un investimento in una competenza, ma un investimento finanziario in un futuro pieno di opportunit\u00e0. Ci auguriamo che questa guida sia un valido punto di partenza e un compagno affidabile nel tuo percorso verso la comprensione dei programmi PLC.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4801d97a e-con-full e-flex e-con e-child\" data-id=\"4801d97a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-701677e8 e-grid e-con-full e-con e-child\" data-id=\"701677e8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f01f135 elementor-widget elementor-widget-heading\" data-id=\"5f01f135\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Dai potenza ai tuoi progetti con i nuovi PLC originali Omron, Mitsubishi e Schneider, disponibili in magazzino e pronti da subito!<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-339c27bf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"339c27bf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi subito una richiesta!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d03a4b4 elementor-widget elementor-widget-heading\" data-id=\"2d03a4b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contattaci<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42706f78 elementor-widget elementor-widget-text-editor\" data-id=\"42706f78\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Basta compilare il tuo nome, indirizzo email e una breve descrizione della tua richiesta in questo modulo. Ti contatteremo entro 24 ore.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ae3d48f elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"5ae3d48f\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 26-02-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"39788\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"5ae3d48f\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessaggio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Messaggio\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_e23480b elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_e23480b\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfQP_ApAAAAAGkOmyxAEbGv0N0eOKw7gxJuRyP5\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OTTIENI PREVENTIVI IMMEDIATI<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2cdb5fbe e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"2cdb5fbe\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-377aee91 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-child\" data-id=\"377aee91\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;motion_fx_range&quot;:&quot;page&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15df2516 elementor-widget elementor-widget-heading\" data-id=\"15df2516\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Categoria di prodotto<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fc2a8b7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1fc2a8b7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/plc\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">PLC<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/hmi\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Interfaccia uomo-macchina<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/servo-motor\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servomotore<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/servo-drive\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servoazionamento<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/omron-sensors\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sensori<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/omron-terminals\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">terminale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/omron-cables\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cavi<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/relay-socket-others\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hand-point-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 199.652c0 23.625-20.65 43.826-44.8 43.826h-99.851c16.34 17.048 18.346 49.766-6.299 70.944 14.288 22.829 2.147 53.017-16.45 62.315C353.574 425.878 322.654 448 272 448c-2.746 0-13.276-.203-16-.195-61.971.168-76.894-31.065-123.731-38.315C120.596 407.683 112 397.599 112 385.786V214.261l.002-.001c.011-18.366 10.607-35.889 28.464-43.845 28.886-12.994 95.413-49.038 107.534-77.323 7.797-18.194 21.384-29.084 40-29.092 34.222-.014 57.752 35.098 44.119 66.908-3.583 8.359-8.312 16.67-14.153 24.918H467.2c23.45 0 44.8 20.543 44.8 43.826zM96 200v192c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V200c0-13.255 10.745-24 24-24h48c13.255 0 24 10.745 24 24zM68 368c0-11.046-8.954-20-20-20s-20 8.954-20 20 8.954 20 20 20 20-8.954 20-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rel\u00e8 e presa<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3909f973 elementor-widget elementor-widget-heading\" data-id=\"3909f973\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Prodotti in saldo<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c4ac4b elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"9c4ac4b\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:end;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:start;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cj1w-eip21s\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/cj1w-eip21s.jpg\" class=\"attachment-full size-full wp-image-39688\" alt=\"cj1w-eip21s\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/cj1w-eip21s.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/cj1w-eip21s-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/cj1w-eip21s-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/cj1w-eip21s-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/cj1w-eip21s-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/cj1w-eip21s-16x12.jpg 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cj1w-eip21s\/\">Omron CJ1W-EIP21S Fast EtherNet\/IP<\/a><\/h4><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7d6b6 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"6d7d6b6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cj1w-crm21\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-CRM21-1.jpg\" class=\"attachment-full size-full wp-image-39666\" alt=\"CJ1W-CRM21\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-CRM21-1.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-CRM21-1-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-CRM21-1-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-CRM21-1-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-CRM21-1-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/CJ1W-CRM21-1-16x12.jpg 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cj1w-crm21\/\">Unit\u00e0 master Omron CompoNet CJ1W-CRM21<\/a><\/h4><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b56e83 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"4b56e83\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/pro-face-pfxgp4201tad-hmi-3-5-touchscreen-in-stock\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/PFXGP4201TAD-5.jpg\" class=\"attachment-full size-full wp-image-39561\" alt=\"PFXGP4201TAD\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/PFXGP4201TAD-5.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/PFXGP4201TAD-5-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/PFXGP4201TAD-5-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/PFXGP4201TAD-5-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/PFXGP4201TAD-5-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/07\/PFXGP4201TAD-5-16x12.jpg 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/pro-face-pfxgp4201tad-hmi-3-5-touchscreen-in-stock\/\">Pro-face GP4201TAD HMI 3,5&quot;<\/a><\/h4><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a6f0ef elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"7a6f0ef\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/weintek-mt8072ip\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/MT8072iP-2.jpg\" class=\"attachment-full size-full wp-image-38422\" alt=\"MT8072iP\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/MT8072iP-2.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/MT8072iP-2-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/MT8072iP-2-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/MT8072iP-2-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/MT8072iP-2-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/MT8072iP-2-16x12.jpg 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/kwoco-plc.com\/it\/product\/weintek-mt8072ip\/\">Weintek 7&quot; HMI MT8072iP con Ethernet<\/a><\/h4><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-554ee279 e-flex e-con-boxed e-con e-parent\" data-id=\"554ee279\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7026ee5a elementor-widget elementor-widget-heading\" data-id=\"7026ee5a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Potresti trovare interessanti anche questi argomenti<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4fbcdd elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"c4fbcdd\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-37834 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-compressed-air tag-pneumatic-components tag-pneumatic-systems\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/pneumatic-systems\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/01\/Pneumatic-Systems-300x195.jpg\" class=\"attachment-medium size-medium wp-image-37840\" alt=\"Sistemi Pneumatici\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/01\/Pneumatic-Systems-300x195.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/01\/Pneumatic-Systems-1024x666.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/01\/Pneumatic-Systems-768x499.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/01\/Pneumatic-Systems-1536x998.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/01\/Pneumatic-Systems-18x12.jpg 18w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/01\/Pneumatic-Systems.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/pneumatic-systems\/\" >\n\t\t\t\tTutto ci\u00f2 che devi sapere sui componenti del sistema pneumatico\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 gennaio 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Questo articolo fornisce una panoramica completa dei sistemi pneumatici, una tecnologia critica nell&#039;automazione industriale. Ci addentreremo nei dettagli del funzionamento di questi sistemi, dei loro componenti chiave e delle loro applicazioni di vasta portata. Leggendo questo articolo, acquisirai una conoscenza approfondita della pneumatica e del motivo per cui \u00e8 indispensabile nel panorama tecnologico odierno.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/pneumatic-systems\/\" aria-label=\"Leggi di pi\u00f9 su Tutto ci\u00f2 che devi sapere sui componenti del sistema pneumatico\" tabindex=\"-1\" >\n\t\t\tPer saperne di pi\u00f9 &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-43584 post type-post status-publish format-standard has-post-thumbnail hentry category-blog category-troubleshooting-resources tag-easybuilder-pro-troubleshooting tag-hmi-plc-communication tag-weintek-plc-no-response\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/weintek-plc-no-response\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/07\/Weintek-HMI-PLC-No-Response-Error-1-300x195.jpg\" class=\"attachment-medium size-medium wp-image-43585\" alt=\"Errore di mancata risposta nel PLC HMI Weinket\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/07\/Weintek-HMI-PLC-No-Response-Error-1-300x195.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/07\/Weintek-HMI-PLC-No-Response-Error-1-1024x666.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/07\/Weintek-HMI-PLC-No-Response-Error-1-768x499.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/07\/Weintek-HMI-PLC-No-Response-Error-1-1536x998.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/07\/Weintek-HMI-PLC-No-Response-Error-1-18x12.jpg 18w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2026\/07\/Weintek-HMI-PLC-No-Response-Error-1.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/weintek-plc-no-response\/\" >\n\t\t\t\tErrore &quot;PLC No Response&quot; dell&#039;HMI Weintek: soluzioni per connessioni seriali ed Ethernet.\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 luglio 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Il messaggio &quot;PLC No Response&quot; dell&#039;HMI Weintek indica che l&#039;HMI non ha ricevuto una risposta valida ad almeno una richiesta del dispositivo entro il tempo configurato. Ci\u00f2 non significa necessariamente che il PLC sia offline.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/weintek-plc-no-response\/\" aria-label=\"Ulteriori informazioni sull&#039;errore &quot;PLC No Response&quot; dell&#039;HMI Weintek: soluzioni per connessioni seriali ed Ethernet\" tabindex=\"-1\" >\n\t\t\tPer saperne di pi\u00f9 &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-34898 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-plc tag-real-time-clocks tag-rtc\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/real-time-clock-rtc-in-plc\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/10\/RTC-in-PLC-300x195.jpg\" class=\"attachment-medium size-medium wp-image-34899\" alt=\"RTC nel PLC\" title=\"\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/10\/RTC-in-PLC-300x195.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/10\/RTC-in-PLC-1024x666.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/10\/RTC-in-PLC-768x499.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/10\/RTC-in-PLC-1536x998.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/10\/RTC-in-PLC-18x12.jpg 18w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/10\/RTC-in-PLC.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/real-time-clock-rtc-in-plc\/\" >\n\t\t\t\tChe cosa \u00e8 un RTC in un PLC? Comprensione degli orologi in tempo reale\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 ottobre 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Gli orologi in tempo reale (RTC) svolgono un ruolo cruciale ma spesso trascurato nell&#039;automazione industriale, garantendo che i controllori logici programmabili (PLC) eseguano con precisione le attivit\u00e0 sensibili al fattore tempo.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/real-time-clock-rtc-in-plc\/\" aria-label=\"Per saperne di pi\u00f9 su Che cos&#039;\u00e8 un RTC in un PLC? Comprensione degli orologi in tempo reale\" tabindex=\"-1\" >\n\t\t\tPer saperne di pi\u00f9 &quot;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nel mondo odierno, in cui l&#039;automazione industriale e la produzione intelligente stanno rivoluzionando il mondo, il Controllore Logico Programmabile (PLC) \u00e8 diventato la &quot;mente&quot; centrale di ogni sistema automatico. Per le persone e le aziende che mirano a entrare o progredire nel campo dell&#039;automazione, padroneggiare i programmi PLC non \u00e8 solo un&#039;abilit\u00e0, ma la chiave del futuro.<\/p>","protected":false},"author":1,"featured_media":39789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,419],"tags":[152,335,137],"class_list":["post-39788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-automation-guides","tag-industrial-automation","tag-industry-4-0","tag-plc-programming"],"_links":{"self":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/posts\/39788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/comments?post=39788"}],"version-history":[{"count":22,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/posts\/39788\/revisions"}],"predecessor-version":[{"id":40897,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/posts\/39788\/revisions\/40897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/media\/39789"}],"wp:attachment":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/media?parent=39788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/categories?post=39788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/tags?post=39788"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}