{"id":36635,"date":"2024-12-03T04:12:29","date_gmt":"2024-12-03T12:12:29","guid":{"rendered":"https:\/\/kwoco-plc.com\/?page_id=36635"},"modified":"2025-04-16T01:50:25","modified_gmt":"2025-04-16T09:50:25","slug":"cp1l-el20dt1-d","status":"publish","type":"page","link":"https:\/\/kwoco-plc.com\/it\/cp1l-el20dt1-d\/","title":{"rendered":"Nuovo CPU Omron CP1L-EL20DT1-D originale disponibile"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"36635\" class=\"elementor elementor-36635\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2053a1 e-flex e-con-boxed e-con e-parent\" data-id=\"b2053a1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36e8e038 rank_math_breadcrumb elementor-widget elementor-widget-shortcode\" data-id=\"36e8e038\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"briciole di pane\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Casa<\/span><\/p><\/nav><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f969f9b e-con-full e-flex e-con e-parent\" data-id=\"6f969f9b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c451b10 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7c451b10\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5be5a665 e-flex e-con-boxed e-con e-parent\" data-id=\"5be5a665\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-73d492b0 e-con-full e-flex e-con e-child\" data-id=\"73d492b0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49f626ad elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"49f626ad\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-carousel.min.css\">\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/12\/cp1l-el20dt1-d.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"49f626ad\" data-elementor-lightbox-title=\"cp1l-el20dt1-d\" data-elementor-lightbox-description=\"cp1l-el20dt1-d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzY2MzYsInVybCI6Imh0dHBzOlwvXC9rd29jby1wbGMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8xMlwvY3AxbC1lbDIwZHQxLWQud2VicCIsInNsaWRlc2hvdyI6IjQ5ZjYyNmFkIn0%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"cp1l-el20dt1-d\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/12\/cp1l-el20dt1-d.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ea7921d e-flex e-con-boxed e-con e-child\" data-id=\"7ea7921d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54406e3d elementor-widget elementor-widget-heading\" data-id=\"54406e3d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Nuovo CPU Omron CP1L-EL20DT1-D originale disponibile<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33ae87b elementor-widget elementor-widget-text-editor\" data-id=\"33ae87b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Alimentazione 24 VDC, 12 ingressi 24 VDC, 8 uscite PNP 0,3 A, 2 ingressi analogici, programma 5K step + memoria dati 10K word, 1 porta Ethernet<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-658ec52 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"658ec52\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 26-02-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"36635\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"658ec52\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t* E-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"* E-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessaggio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"7\" placeholder=\"Messaggio\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_e079494 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_e079494\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfQP_ApAAAAAGkOmyxAEbGv0N0eOKw7gxJuRyP5\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inviare<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36404bc2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"36404bc2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-290c1096 e-flex e-con-boxed e-con e-parent\" data-id=\"290c1096\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42c217d0 elementor-widget elementor-widget-heading\" data-id=\"42c217d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PLC digitale Omron CP1L-EL20DT1-D con Ethernet <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27b1f28a elementor-widget elementor-widget-text-editor\" data-id=\"27b1f28a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Prova un&#039;automazione e un controllo senza pari con il PLC digitale Omron CP1L-EL20DT1-D. Progettato per applicazioni industriali che richiedono precisione e affidabilit\u00e0, questo controllore logico programmabile offre funzionalit\u00e0 avanzate per semplificare le tue operazioni. Disponibile in magazzino e pronto per la consegna globale entro 24 ore, \u00e8 la soluzione perfetta per migliorare i tuoi processi di automazione.<\/p><p>Scopri di pi\u00f9 sui PLC Omron sul nostro <a href=\"https:\/\/kwoco-plc.com\/it\/omron-plc\/\">Pagina PLC Omron<\/a>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27bd83f1 elementor-widget elementor-widget-html\" data-id=\"27bd83f1\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"overflow-x: auto; width: 100%; font-family: oswald;\">\n<table>\n<thead>\n<tr>\n<th><strong>Specificazione<\/strong><\/th>\n<th><strong>Dettagli<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Modello<\/td>\n<td>Modello CP1L-EL20DT1-D<\/td>\n<\/tr>\n<tr>\n<td>Produttore<\/td>\n<td>Omron<\/td>\n<\/tr>\n<tr>\n<td>Alimentazione elettrica<\/td>\n<td>24 V CC<\/td>\n<\/tr>\n<tr>\n<td>Tipo di montaggio<\/td>\n<td>Guida DIN<\/td>\n<\/tr>\n<tr>\n<td>Ingressi digitali<\/td>\n<td>8 volte<\/td>\n<\/tr>\n<tr>\n<td>Uscite digitali<\/td>\n<td>12 volte<\/td>\n<\/tr>\n<tr>\n<td>Ingressi analogici<\/td>\n<td>2 ingressi analogici<\/td>\n<\/tr>\n<tr>\n<td>Uscite analogiche<\/td>\n<td>2 x uscite analogiche<\/td>\n<\/tr>\n<tr>\n<td>Porte di comunicazione<\/td>\n<td>Etereo<\/td>\n<\/tr>\n<tr>\n<td>Capacit\u00e0 di memoria<\/td>\n<td>Memoria estesa<\/td>\n<\/tr>\n<tr>\n<td>Linguaggio di programmazione<\/td>\n<td>Logica a scala<\/td>\n<\/tr>\n<tr>\n<td>Compatibilit\u00e0 software<\/td>\n<td>CX-Uno<\/td>\n<\/tr>\n<tr>\n<td>Temperatura di esercizio<\/td>\n<td>-10\u00b0C a 55\u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Temperatura di conservazione<\/td>\n<td>-20\u00b0C a 75\u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Dimensioni<\/td>\n<td>Design compatto<\/td>\n<\/tr>\n<tr>\n<td>Peso<\/td>\n<td>Circa 350g<\/td>\n<\/tr>\n<tr>\n<td>Certificazione<\/td>\n<td>CE, UL<\/td>\n<\/tr>\n<tr>\n<td>Funzionalit\u00e0 di sicurezza<\/td>\n<td>Protezione tramite password<\/td>\n<\/tr>\n<tr>\n<td>Disponibilit\u00e0<\/td>\n<td>In magazzino<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb5efb elementor-widget elementor-widget-heading\" data-id=\"5bb5efb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Controllo di automazione avanzato con Omron CP1L-EL20DT1-D<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5171ebf5 elementor-widget elementor-widget-text-editor\" data-id=\"5171ebf5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>L&#039;Omron CP1L-EL20DT1-D \u00e8 un PLC compatto ma potente che offre prestazioni eccezionali nell&#039;automazione industriale. Fornisce un controllo preciso su sistemi complessi, rendendolo un componente ideale per migliorare l&#039;efficienza e la produttivit\u00e0.<\/p><p>Grazie alla sua robusta capacit\u00e0 di memoria, puoi archiviare programmi e dati estesi, assicurandoti che le tue attivit\u00e0 di automazione vengano eseguite in modo impeccabile. La capacit\u00e0 del PLC di gestire una programmazione complessa lo rende uno strumento versatile in qualsiasi configurazione di automazione.<\/p><p>Cerchi altre opzioni PLC? Visita il nostro <a href=\"https:\/\/kwoco-plc.com\/it\/plc\/\">Raccolta PLC<\/a>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19f7edb elementor-widget elementor-widget-heading\" data-id=\"19f7edb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Connettivit\u00e0 Ethernet senza interruzioni per un accesso migliorato<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c8c5920 elementor-widget elementor-widget-text-editor\" data-id=\"4c8c5920\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Dotato di funzionalit\u00e0 Ethernet integrate, il CP1L-EL20DT1-D consente un&#039;integrazione di rete senza soluzione di continuit\u00e0. Questa funzionalit\u00e0 semplifica il monitoraggio e la programmazione da remoto, consentendoti di accedere ai tuoi sistemi in qualsiasi momento e ovunque. La connettivit\u00e0 avanzata garantisce una rapida risoluzione dei problemi e tempi di inattivit\u00e0 minimi, aiutandoti a risolvere i problemi tempestivamente.<\/p><p>Sfruttando la comunicazione Ethernet, puoi trasmettere dati in modo efficiente, migliorando il flusso di lavoro operativo complessivo. Questa connettivit\u00e0 \u00e8 fondamentale per gli ambienti industriali moderni in cui lo scambio di dati in tempo reale \u00e8 essenziale.<\/p><p>Migliora le tue interfacce con <a href=\"https:\/\/kwoco-plc.com\/it\/omron-hmi\/\">HMI Omron<\/a>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2edf4ec8 elementor-widget elementor-widget-heading\" data-id=\"2edf4ec8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Design compatto su guida DIN e alimentazione a 24 V CC<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e59538b elementor-widget elementor-widget-text-editor\" data-id=\"e59538b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il CP1L-EL20DT1-D vanta un design compatto su guida DIN, che rende l&#039;installazione semplice e salvaspazio. Il suo profilo sottile \u00e8 perfetto per i pannelli di controllo con spazio limitato, ma non scende a compromessi sulle prestazioni.<\/p><p>Funzionante con un&#039;alimentazione a 24 V CC, questo PLC \u00e8 efficiente dal punto di vista energetico e compatibile con i sistemi di alimentazione industriali standard. La sua affidabilit\u00e0 garantisce un funzionamento continuo, essenziale per mantenere la produttivit\u00e0 in ambienti esigenti.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98fbb25 elementor-widget elementor-widget-heading\" data-id=\"98fbb25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perch\u00e9 scegliere Omron CP1L-EL20DT1-D?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c5477 elementor-widget elementor-widget-text-editor\" data-id=\"74c5477\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Efficienza: semplifica i tuoi processi di automazione con elaborazione ad alta velocit\u00e0 e prestazioni affidabili.<\/li><li>Connettivit\u00e0: integrazione Ethernet perfetta per l&#039;accesso e il controllo remoto.<\/li><li>Versatilit\u00e0: adatto a varie applicazioni grazie alla combinazione di I\/O digitali e analogici.<\/li><li>Affidabilit\u00e0: realizzato con componenti durevoli per ridurre al minimo i tempi di fermo e risolvere gli errori operativi.<\/li><li>Supporto: forniamo assistenza tecnica completa e accessori per soddisfare le vostre esigenze.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-118f8862 elementor-widget elementor-widget-heading\" data-id=\"118f8862\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scheda tecnica del prodotto CP1L-EL20DT1-D<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6db4a401 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"6db4a401\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/files.omron.eu\/downloads\/latest\/datasheet\/en\/p081_cp-series_cp1l_cpu_unit_datasheet_en.pdf?v=1\" target=\"_blank\" class=\"elementor-icon elementor-animation-\" tabindex=\"-1\" rel=\"nofollow noopener\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/files.omron.eu\/downloads\/latest\/datasheet\/en\/p081_cp-series_cp1l_cpu_unit_datasheet_en.pdf?v=1\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t\tScheda tecnica dell&#039;unit\u00e0 CPU CP1L serie CP.pdf\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298bc0bd elementor-widget elementor-widget-heading\" data-id=\"298bc0bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Domande frequenti<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e9b8ce elementor-widget elementor-widget-accordion\" data-id=\"3e9b8ce\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-accordion{text-align:start}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quale software di programmazione \u00e8 compatibile con CP1L-EL20DT1-D?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6561\"><p>Il PLC \u00e8 compatibile con il software CX-One di Omron, che fornisce strumenti completi per la programmazione e la configurazione.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6562\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6562\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Posso espandere le capacit\u00e0 I\/O di questo PLC?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6562\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6562\"><p>S\u00ec, il CP1L-EL20DT1-D supporta moduli di espansione, consentendo di aumentare gli I\/O digitali e analogici in base alle esigenze.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6563\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-6563\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c8 disponibile supporto tecnico per l&#039;installazione e la programmazione?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6563\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-6563\"><p>Assolutamente! Contattateci per ricevere assistenza da esperti per l&#039;installazione, la programmazione e la risoluzione dei problemi.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6564\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-6564\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Il PLC \u00e8 dotato di funzionalit\u00e0 di sicurezza per proteggere i miei programmi?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6564\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-6564\"><p>S\u00ec, include funzionalit\u00e0 di sicurezza come la protezione tramite password per salvaguardare i tuoi programmi e dati.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6565\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-6565\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quanto velocemente posso ricevere il mio ordine?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6565\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-6565\"><p>Disponiamo di un gran numero di nuovi stock originali e possiamo garantire la consegna in tutto il mondo entro 24 ore.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What programming software is compatible with the CP1L-EL20DT1-D?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>The PLC is compatible with Omron&#8217;s CX-One software, which provides comprehensive tools for programming and configuration.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Can I expand the I\\\/O capabilities of this PLC?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Yes, the CP1L-EL20DT1-D supports expansion modules, allowing you to increase digital and analog I\\\/O as needed.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Is technical support available for installation and programming?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Absolutely! Please contact us for expert assistance with setup, programming, and troubleshooting.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Does the PLC have security features to protect my programs?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Yes, it includes security features like password protection to safeguard your programs and data.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"How quickly can I receive my order?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>We have a large number of new original stocks and can support global delivery within 24 hours.<\\\/p>\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-185f3d44 e-flex e-con-boxed e-con e-parent\" data-id=\"185f3d44\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f3c8d14 e-con-full e-flex e-con e-child\" data-id=\"f3c8d14\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2311fcb9 e-flex e-con-boxed e-con e-child\" data-id=\"2311fcb9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-583d95da elementor-widget elementor-widget-heading\" data-id=\"583d95da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prodotto correlato<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d1ea8c2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7d1ea8c2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-543f8bdb elementor-grid-4 elementor-grid-mobile-2 elementor-posts__hover-none elementor-grid-tablet-2 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-widget elementor-widget-posts\" data-id=\"543f8bdb\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_mobile&quot;:&quot;2&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;cards_masonry&quot;:&quot;yes&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26663 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/product\/cj2m-cpu13\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu13-5.webp\" class=\"attachment-full size-full wp-image-26668\" alt=\"cj2m-cpu13\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu13-5.webp 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu13-5-300x225.webp 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu13-5-1024x768.webp 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu13-5-768x576.webp 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu13-5-1536x1152.webp 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/product\/cj2m-cpu13\/\">\n\t\t\t\tUnit\u00e0 CPU Omron CJ2M-CPU13\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/product\/cj2m-cpu13\/\" aria-label=\"Per saperne di pi\u00f9 sull&#039;unit\u00e0 CPU Omron CJ2M-CPU13\" tabindex=\"-1\">\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-9496 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-ethernet-ip-unit-cs1w-eip21\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"960\" height=\"721\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1w-eip21.jpg\" class=\"attachment-full size-full wp-image-9501\" alt=\"cs1w-eip21\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1w-eip21.jpg 960w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1w-eip21-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cs1w-eip21-768x577.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-ethernet-ip-unit-cs1w-eip21\/\">\n\t\t\t\tUnit\u00e0 IP Ethernet Omron CS1W-EIP21\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-ethernet-ip-unit-cs1w-eip21\/\" aria-label=\"Per saperne di pi\u00f9 su Omron Ethernet IP Unit CS1W-EIP21\" tabindex=\"-1\">\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-149 page type-page status-publish has-post-thumbnail hentry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/plc\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/plc.jpg\" class=\"attachment-full size-full wp-image-38298\" alt=\"societ\u00e0 a responsabilit\u00e0 limitata\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/plc.jpg 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/plc-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/plc-1024x769.jpg 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/plc-768x576.jpg 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/plc-1536x1153.jpg 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/03\/plc-16x12.jpg 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/plc\/\">\n\t\t\t\tPLC\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/plc\/\" aria-label=\"Per saperne di pi\u00f9 su PLC\" tabindex=\"-1\">\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-10538 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cp1l-cpu-unit-cp1l-em40dr-d\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"721\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1l-em40dr-d.jpg\" class=\"attachment-full size-full wp-image-10542\" alt=\"cp1l-em40dr-d\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1l-em40dr-d.jpg 960w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1l-em40dr-d-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1l-em40dr-d-768x577.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cp1l-cpu-unit-cp1l-em40dr-d\/\">\n\t\t\t\tUnit\u00e0 CPU Omron CP1L CP1L-EM40DR-D\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cp1l-cpu-unit-cp1l-em40dr-d\/\" aria-label=\"Per saperne di pi\u00f9 su Omron CP1L CPU Unit CP1L-EM40DR-D\" tabindex=\"-1\">\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f80b575 e-con-full e-flex e-con e-child\" data-id=\"1f80b575\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-22352f6b e-flex e-con-boxed e-con e-child\" data-id=\"22352f6b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec496f2 elementor-widget elementor-widget-heading\" data-id=\"ec496f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tutte le tue esigenze di controllo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fe28b58 elementor-widget elementor-widget-text-editor\" data-id=\"5fe28b58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Non riesci a trovare il tuo marchio? Contattaci per un&#039;assistenza personalizzata.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ace8023 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2ace8023\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi informazioni ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuova CPU Omron CP1L-EL20DT1-D originale in magazzino, alimentazione 24 VDC, 12 ingressi 24 VDC, 8 uscite PNP 0,3 A, 2 ingressi analogici,<\/p>","protected":false},"author":1,"featured_media":36636,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[56,16,7,70],"_links":{"self":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages\/36635"}],"collection":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/comments?post=36635"}],"version-history":[{"count":23,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages\/36635\/revisions"}],"predecessor-version":[{"id":38611,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages\/36635\/revisions\/38611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/media\/36636"}],"wp:attachment":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/media?parent=36635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/categories?post=36635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/tags?post=36635"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}