{"id":26477,"date":"2024-06-12T19:37:47","date_gmt":"2024-06-13T03:37:47","guid":{"rendered":"https:\/\/kwoco-plc.com\/?page_id=26477"},"modified":"2025-01-08T00:48:09","modified_gmt":"2025-01-08T08:48:09","slug":"cj1w-nc113","status":"publish","type":"page","link":"https:\/\/kwoco-plc.com\/it\/product\/cj1w-nc113\/","title":{"rendered":"Unit\u00e0 di controllo della posizione Omron CJ1W-NC113"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"26477\" class=\"elementor elementor-26477\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-604d1a78 e-flex e-con-boxed e-con e-parent\" data-id=\"604d1a78\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ad86424 rank_math_breadcrumb elementor-widget elementor-widget-shortcode\" data-id=\"6ad86424\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"briciole di pane\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Casa<\/span><\/p><\/nav><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3eb3102e e-con-full e-flex e-con e-parent\" data-id=\"3eb3102e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7cd70e54 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7cd70e54\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a33f084 e-flex e-con-boxed e-con e-parent\" data-id=\"2a33f084\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3d8569c6 e-flex e-con-boxed e-con e-child\" data-id=\"3d8569c6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec3d639 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"2ec3d639\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-carousel.min.css\">\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj1w-nc113.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ec3d639\" data-elementor-lightbox-title=\"cj1w-nc113\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY0ODAsInVybCI6Imh0dHBzOlwvXC9rd29jby1wbGMuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvY2oxdy1uYzExMy53ZWJwIiwic2xpZGVzaG93IjoiMmVjM2Q2MzkifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"cj1w-nc113\" style=\"background-image: url(&#039;https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj1w-nc113.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e198157 e-flex e-con-boxed e-con e-child\" data-id=\"e198157\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d01aad5 elementor-widget elementor-widget-heading\" data-id=\"2d01aad5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Unit\u00e0 di controllo della posizione Omron CJ1W-NC113<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b51cb3 elementor-widget elementor-widget-heading\" data-id=\"68b51cb3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Unit\u00e0 di controllo della posizione, 1 asse, uscita impulsi, collettore aperto<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6585a6f2 elementor-widget elementor-widget-html\" data-id=\"6585a6f2\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"overflow-x: auto;width: 100%;font-family: oswald;\">\r\n<table>\r\n    <tr>\r\n        <td>Marca<\/td>\r\n        <td>Omron<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>Numero di modello<\/td>\r\n        <td>Codice articolo: CJ1W-NC113<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>Stato<\/td>\r\n        <td>In magazzino<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>Condizione<\/td>\r\n        <td>Nuovo Originale<\/td>\r\n    <\/tr>\r\n    <tr>\r\n        <td>Garanzia<\/td>\r\n        <td>12 mesi<\/td>\r\n    <\/tr>   \r\n<\/table>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-522852a2 elementor-widget elementor-widget-button\" data-id=\"522852a2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ottieni un preventivo immediato<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5174682a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5174682a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a5a384 e-flex e-con-boxed e-con e-child\" data-id=\"3a5a384\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8485a89 e-flex e-con-boxed e-con e-child\" data-id=\"8485a89\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3d6aad elementor-widget elementor-widget-heading\" data-id=\"d3d6aad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Categorie<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b8c40f elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2b8c40f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Omron,<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Modello Omron CJ1W<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-470f937 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"470f937\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d9ece2 e-flex e-con-boxed e-con e-child\" data-id=\"7d9ece2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f03cb59 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"f03cb59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Garanzia globale<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0241e31 elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0241e31\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/08\/100-new-original.png\" class=\"attachment-full size-full wp-image-30355\" alt=\"100% nuovo originale\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-676fd52 elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"676fd52\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/08\/12-months-warranty.png\" class=\"attachment-full size-full wp-image-30356\" alt=\"Garanzia di 12 mesi\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60e9740 elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"60e9740\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/08\/wordwide-shipping.png\" class=\"attachment-full size-full wp-image-30357\" alt=\"spedizione in tutto il mondo\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55ab89fd e-flex e-con-boxed e-con e-parent\" data-id=\"55ab89fd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7428aa5c e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"7428aa5c\" data-element_type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"194\" aria-label=\"Schede. Apri gli elementi con Invio o Spazio, chiudili con Esc e naviga con i tasti freccia.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t\t\t<button id=\"e-n-tabs-title-1941\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1941\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t\tParametri del prodotto\t\t\t\t<\/span>\n\t\t\t<\/button>\n\t\t\t\t\t<button id=\"e-n-tabs-title-1942\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1942\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t\tScheda dati\t\t\t\t<\/span>\n\t\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1941\" role=\"tabpanel\" aria-labelledby=\"e-n-tabs-title-1941\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-ab245fe e-con-full e-flex e-con e-child\" data-id=\"ab245fe\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-130a3523 elementor-widget elementor-widget-text-editor\" data-id=\"130a3523\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 22-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div style=\"overflow-x: auto; width: 100%; font-family: oswald;\">\n<table>\n<tbody>\n<tr>\n<td  colspan=\"2\" rowspan=\"2\"><strong>Articolo<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\"><strong>Modello<\/strong><\/td>\n<\/tr>\n<tr>\n<td ><strong>Modello CJ1W-NC113\/133<\/strong><\/td>\n<td ><strong>Modello CJ1W-NC213\/233<\/strong><\/td>\n<td ><strong>Modello CJ1W-NC413\/433<\/strong><\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Modelli PLC applicabili<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">PLC serie CJ *1<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Tipo di unit\u00e0<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Unit\u00e0 I\/O speciale<\/td>\n<\/tr>\n<tr>\n<td ><strong>Requisiti I\/O<\/strong><\/td>\n<td ><strong>Parole<\/strong><\/td>\n<td >5 parole<\/td>\n<td >10 parole<\/td>\n<td >20 parole<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Conducente controllato<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">I modelli NC113\/213\/413 con ingresso a treno di impulsi Servo Drive o driver motore passo-passo hanno un&#039;uscita a collettore aperto. I modelli NC133\/233\/433 hanno un&#039;uscita line driver.<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"1\" rowspan=\"2\"><strong>Controllare<\/strong><\/td>\n<td ><strong>Sistema di controllo<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Controllo ad anello aperto tramite uscita a treno di impulsi<\/td>\n<\/tr>\n<tr>\n<td ><strong>Numero di assi di controllo<\/strong><\/td>\n<td >1 asse<\/td>\n<td >2 assi<\/td>\n<td >4 assi<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Unit\u00e0 di controllo<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Impulso<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Operazioni di posizionamento<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Due tipi: operazione di memoria e operazione diretta<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"1\" rowspan=\"4\"><strong>Operazioni di posizionamento<\/strong><\/td>\n<td ><strong>Indipendente<\/strong><\/td>\n<td >1 asse<\/td>\n<td >2 assi indipendenti<\/td>\n<td >4 assi indipendenti<\/td>\n<\/tr>\n<tr>\n<td ><strong>Interpolazione lineare<\/strong><\/td>\n<td >Nessuno<\/td>\n<td >2 assi max.<\/td>\n<td >4 assi max.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Controllo della velocit\u00e0<\/strong><\/td>\n<td >1 asse<\/td>\n<td >2 assi indipendenti<\/td>\n<td >4 assi indipendenti<\/td>\n<\/tr>\n<tr>\n<td ><strong>Interrompere l&#039;alimentazione<\/strong><\/td>\n<td >1 asse<\/td>\n<td >2 assi indipendenti<\/td>\n<td >4 assi indipendenti<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"1\" rowspan=\"2\"><strong>Posizioni<\/strong><\/td>\n<td ><strong>Allineare<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">-1.073.741.823 a 1.073.741.823 impulsi *2<\/td>\n<\/tr>\n<tr>\n<td ><strong>Elementi di dati<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">100\/asse<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"1\" rowspan=\"2\"><strong>Velocit\u00e0<\/strong><\/td>\n<td ><strong>Allineare<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Da 1 pps a 500 kpps<\/td>\n<\/tr>\n<tr>\n<td ><strong>Elementi di dati<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">100\/asse<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"1\" rowspan=\"2\"><strong>Tempi di accelerazione e decelerazione<\/strong><\/td>\n<td ><strong>Allineare<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Da 0 a 250 s, fino al raggiungimento della velocit\u00e0 massima.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Elementi di dati<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">9\/asse per accelerazione e decelerazione ciascuno<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"1\" rowspan=\"13\"><strong>Funzioni e impostazioni<\/strong><\/td>\n<td ><strong>Ricerca origine<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Segnale di ingresso di prossimit\u00e0 dell&#039;origine: selezionabile (contatto assente, NO o NC). Segnale di ingresso di origine: selezionabile (contatto NO o NC) Compensazione dell&#039;origine: da -1.073.741.823 a 1.073.741.823 impulsi Velocit\u00e0 di ricerca dell&#039;origine: \u00e8 possibile impostare velocit\u00e0 elevata o di prossimit\u00e0. Metodo di rilevamento dell&#039;origine: pu\u00f2 essere impostato per arrestarsi sul segnale di ingresso dell&#039;origine dopo che il segnale di ingresso di prossimit\u00e0 \u00e8 stato attivato, per arrestarsi sul segnale di ingresso dell&#039;origine dopo che il segnale di ingresso di prossimit\u00e0 \u00e8 stato disattivato, per arrestarsi sul segnale di ingresso dell&#039;origine senza utilizzare il segnale di ingresso di prossimit\u00e0 o per arrestarsi sul segnale di ingresso dell&#039;origine dopo che il segnale di ingresso limite \u00e8 stato disattivato. NO = Normalmente aperto NC = Normalmente chiuso<\/td>\n<\/tr>\n<tr>\n<td ><strong>Jogging<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Il jogging pu\u00f2 essere eseguito a una velocit\u00e0 specificata.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Tempi di permanenza<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">19\/asse pu\u00f2 essere impostato da 0 a 9,99 s (unit\u00e0: 0,01 s).<\/td>\n<\/tr>\n<tr>\n<td ><strong>Curve di accelerazione\/decelerazione<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Trapezoidale o curva a S (pu\u00f2 essere impostato separatamente per ciascun asse.)<\/td>\n<\/tr>\n<tr>\n<td ><strong>Zone<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Il flag di zona si attiva quando la posizione attuale \u00e8 all&#039;interno di una zona specificata. \u00c8 possibile impostare tre zone per ogni asse.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Limiti del software<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Pu\u00f2 essere impostato entro un intervallo compreso tra -1.073.741.823 e 1.073.741.823 impulsi.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Compensazione del gioco<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Da 0 a 9.999 impulsi. \u00c8 possibile impostare anche la velocit\u00e0 di compensazione.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Insegnamento<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Con un comando dal PLC, la posizione attuale pu\u00f2 essere presa come dato di posizione.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Arresto di decelerazione<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Il comando STOP determina la decelerazione del posizionamento fino all&#039;arresto in base al tempo di decelerazione specificato.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Arresto di emergenza<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Le uscite a impulsi vengono interrotte da un comando di arresto di emergenza esterno.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Posizione attuale preimpostata<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Il comando PRESET POSIZIONE PRESENTE pu\u00f2 essere utilizzato per modificare la posizione attuale in un valore specificato.<\/td>\n<\/tr>\n<tr>\n<td ><strong>Ignora<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Quando il comando di abilitazione override tde viene eseguito durante il posizionamento, la velocit\u00e0 target tde viene modificata applicando il coefficiente override tde. \u00c8 possibile impostare un valore da 1 a 999% (con un incremento di 1%)<\/td>\n<\/tr>\n<tr>\n<td ><strong>Salvataggio dei dati<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">1) Salvataggio nella memoria flash. (Pu\u00f2 essere scritto 100.000 volte.) 2) Lettura dall&#039;area PLC tramite istruzione di lettura dati. 3) Lettura tramite software di supporto e salvataggio sul disco rigido del computer o sul floppy disk.<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"1\" rowspan=\"2\"><strong>I\/O esterno<\/strong><\/td>\n<td ><strong>Ingressi<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Preparare i seguenti input per ciascun asse: segnali di input limite CW e CCW, segnale di input prossimit\u00e0 origine, segnale di input origine, segnale di input arresto di emergenza, segnale di posizionamento completato, segnale di input interruzione<\/td>\n<\/tr>\n<tr>\n<td ><strong>Risultati<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Preparare le seguenti uscite per ciascun asse: uscite impulsi impulsi CW\/CCW, uscite impulsi e uscite direzione possono essere commutate. \u00c8 possibile selezionare le uscite di comando di reset del contatore di errori o di regolazione dell&#039;origine a seconda della modalit\u00e0 tde.<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Periodo di distribuzione dell&#039;uscita impulsiva<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Funzionamento a 1 asse: 4 ms Interpolazione lineare: 8 ms<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Tempo di risposta<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Fare riferimento al Manuale operativo, Appendice A Caratteristiche delle prestazioni.<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Funzione di autodiagnosi<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Controllo della memoria flash, controllo della perdita di memoria, controllo del bus della CPU<\/td>\n<\/tr>\n<tr>\n<td  colspan=\"2\" rowspan=\"1\"><strong>Funzione di rilevamento degli errori<\/strong><\/td>\n<td  colspan=\"3\" rowspan=\"1\">Overtravel, errore CPU, limite software superato, arresto di emergenza<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1942\" role=\"tabpanel\" aria-labelledby=\"e-n-tabs-title-1942\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-44879339 e-con-full e-flex e-con e-child\" data-id=\"44879339\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71c4f9c8 elementor-widget elementor-widget-image\" data-id=\"71c4f9c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"353\" height=\"490\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1.webp\" class=\"attachment-full size-full wp-image-35721\" alt=\"SCHEDA DATI\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1.webp 353w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1-216x300.webp 216w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/11\/DATASHEET-1-9x12.webp 9w\" sizes=\"(max-width: 353px) 100vw, 353px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41d7a2bd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"41d7a2bd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cj1-cj2-datasheet.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download gratuito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6354040e e-flex e-con-boxed e-con e-parent\" data-id=\"6354040e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dc16108 e-con-full e-flex e-con e-child\" data-id=\"dc16108\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1c4a10bb e-flex e-con-boxed e-con e-child\" data-id=\"1c4a10bb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d8a5434 elementor-widget elementor-widget-heading\" data-id=\"7d8a5434\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prodotto correlato<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f786b65 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7f786b65\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-160ccbb7 elementor-grid-4 elementor-grid-mobile-2 elementor-posts__hover-none elementor-grid-tablet-2 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-widget elementor-widget-posts\" data-id=\"160ccbb7\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;4&quot;,&quot;cards_columns_mobile&quot;:&quot;2&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-10137 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-analog-input-unit-cp1w-ad041\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"721\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1w-ad041.jpg\" class=\"attachment-full size-full wp-image-10150\" alt=\"cp1w-ad041\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1w-ad041.jpg 960w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1w-ad041-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/cp1w-ad041-768x577.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-analog-input-unit-cp1w-ad041\/\" >\n\t\t\t\tUnit\u00e0 di ingresso analogico Omron CP1W-AD041\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-analog-input-unit-cp1w-ad041\/\" aria-label=\"Per saperne di pi\u00f9 su Unit\u00e0 di ingresso analogico Omron CP1W-AD041\" tabindex=\"-1\" >\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-38141 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cp2e-n40dt1-d\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1441\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/02\/CP2E-N40DT1-D-4.webp\" class=\"attachment-full size-full wp-image-38144\" alt=\"Modello CP2E-N40DT1-D\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/02\/CP2E-N40DT1-D-4.webp 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/02\/CP2E-N40DT1-D-4-300x225.webp 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/02\/CP2E-N40DT1-D-4-1024x769.webp 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/02\/CP2E-N40DT1-D-4-768x576.webp 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/02\/CP2E-N40DT1-D-4-1536x1153.webp 1536w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2025\/02\/CP2E-N40DT1-D-4-16x12.webp 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cp2e-n40dt1-d\/\" >\n\t\t\t\tNuovo PLC compatto originale Omron CP2E-N40DT1-D\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-cp2e-n40dt1-d\/\" aria-label=\"Leggi di pi\u00f9 sul nuovo PLC compatto originale Omron CP2E-N40DT1-D\" tabindex=\"-1\" >\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-26677 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/product\/cj2m-cpu35\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu35-5.webp\" class=\"attachment-full size-full wp-image-26681\" alt=\"cj2m-cpu35 (5)\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu35-5.webp 1920w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu35-5-300x225.webp 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu35-5-1024x768.webp 1024w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu35-5-768x576.webp 768w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/06\/cj2m-cpu35-5-1536x1152.webp 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/product\/cj2m-cpu35\/\" >\n\t\t\t\tUnit\u00e0 CPU Omron CJ2M-CPU35\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/product\/cj2m-cpu35\/\" aria-label=\"Per saperne di pi\u00f9 sull&#039;unit\u00e0 CPU Omron CJ2M-CPU35\" tabindex=\"-1\" >\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-942 page type-page status-publish has-post-thumbnail hentry tag-omron tag-omron-plc tag-plc tag-products\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-output-unit-nx-da3605\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"721\" src=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx-da3605.jpg\" class=\"attachment-full size-full wp-image-945\" alt=\"nx-da3605\" srcset=\"https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx-da3605.jpg 960w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx-da3605-300x225.jpg 300w, https:\/\/kwoco-plc.com\/wp-content\/uploads\/2024\/05\/nx-da3605-768x577.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-output-unit-nx-da3605\/\" >\n\t\t\t\tUnit\u00e0 di uscita OMRON NX-DA3605\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/kwoco-plc.com\/it\/product\/omron-output-unit-nx-da3605\/\" aria-label=\"Per saperne di pi\u00f9 su OMRON Output Unit NX-DA3605\" tabindex=\"-1\" >\n\t\t\tVisualizza altro \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50a3f015 e-con-full e-flex e-con e-child\" data-id=\"50a3f015\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-75e9cdf5 e-flex e-con-boxed e-con e-child\" data-id=\"75e9cdf5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61729784 elementor-widget elementor-widget-heading\" data-id=\"61729784\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tutte le tue esigenze di controllo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697ad47d elementor-widget elementor-widget-text-editor\" data-id=\"697ad47d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Non riesci a trovare il tuo marchio? Contattaci per un&#039;assistenza personalizzata.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e2edb4e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5e2edb4e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi informazioni ora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ead9238 e-flex e-con-boxed e-con e-parent\" data-id=\"1ead9238\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5c084622 e-flex e-con-boxed e-con e-child\" data-id=\"5c084622\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-638c145b e-flex e-con-boxed e-con e-child\" data-id=\"638c145b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-751ea6b elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"751ea6b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/kwoco-plc.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-th\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M149.333 56v80c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24V56c0-13.255 10.745-24 24-24h101.333c13.255 0 24 10.745 24 24zm181.334 240v-80c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24h101.333c13.256 0 24.001-10.745 24.001-24zm32-240v80c0 13.255 10.745 24 24 24H488c13.255 0 24-10.745 24-24V56c0-13.255-10.745-24-24-24H386.667c-13.255 0-24 10.745-24 24zm-32 80V56c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24h101.333c13.256 0 24.001-10.745 24.001-24zm-205.334 56H24c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24zM0 376v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H24c-13.255 0-24 10.745-24 24zm386.667-56H488c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H386.667c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24zm0 160H488c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H386.667c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24zM181.333 376v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInizia oggi stesso!\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSBLOCCA SOLUZIONI EFFICIENTI \u2013 INVIA LA TUA RICHIESTA PER ASSISTENZA IMMEDIATA.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-506905e6 elementor-widget elementor-widget-text-editor\" data-id=\"506905e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Intraprendi con noi un viaggio di approvvigionamento senza intoppi. Se stai cercando un preventivo per un prodotto o necessiti di ulteriore supporto, il nostro team \u00e8 qui per guidarti in ogni fase del percorso.<\/p><p>Compila questo modulo per avviare una conversazione su misura per le tue esigenze specifiche. Comprendiamo il valore del tuo progetto e del tuo tempo.<\/p><p>Non preoccuparti, le tue informazioni e-mail rimangono strettamente riservate con noi. Collaboriamo per migliorare le tue operazioni oggi stesso.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63c63769 e-flex e-con-boxed e-con e-child\" data-id=\"63c63769\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a45843 elementor-widget elementor-widget-heading\" data-id=\"4a45843\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Richiedi un preventivo adesso!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94d909c elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-22716 elementor-widget-form\" data-id=\"94d909c\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.19.0 - 26-02-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"26477\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"94d909c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessaggio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Messaggio\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_cb8daa8 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_cb8daa8\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfQP_ApAAAAAGkOmyxAEbGv0N0eOKw7gxJuRyP5\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon-right elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-telegram-plane\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M446.7 98.6l-67.6 318.8c-5.1 22.5-18.4 28.1-37.3 17.5l-103-75.9-49.7 47.8c-5.5 5.5-10.1 10.1-20.7 10.1l7.4-104.9 190.9-172.5c8.3-7.4-1.8-11.5-12.9-4.1L117.8 284 16.2 252.2c-22.1-6.9-22.5-22.1 4.6-32.7L418.2 66.4c18.4-6.9 34.5 4.1 28.5 32.2z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inviare<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Unit\u00e0 di controllo posizione Omron CJ1W-NC113 Unit\u00e0 di controllo posizione, 1 asse, uscita impulsi, collettore aperto Marca Omron Numero modello CJ1W-NC113 Stato Disponibile Condizione Nuovo Originale Garanzia<\/p>","protected":false},"author":1,"featured_media":26480,"parent":76,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[56,16,7,70],"_links":{"self":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages\/26477"}],"collection":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/comments?post=26477"}],"version-history":[{"count":25,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages\/26477\/revisions"}],"predecessor-version":[{"id":36056,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages\/26477\/revisions\/36056"}],"up":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/pages\/76"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/media\/26480"}],"wp:attachment":[{"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/media?parent=26477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/categories?post=26477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kwoco-plc.com\/it\/wp-json\/wp\/v2\/tags?post=26477"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}